{"id":8273,"date":"2025-06-27T09:58:49","date_gmt":"2025-06-27T09:58:49","guid":{"rendered":"https:\/\/mirus.ch\/mirus-prognolite\/"},"modified":"2026-08-18T07:04:14","modified_gmt":"2026-08-18T07:04:14","slug":"mirus-prognolite","status":"publish","type":"page","link":"https:\/\/mirus.ch\/fr\/produits\/mirus-prognolite\/","title":{"rendered":"Mirus Prognolite"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"8273\" class=\"elementor elementor-8273 elementor-7491\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-25d732c e-con-full e-flex e-con e-parent\" data-id=\"25d732c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-33ee95de e-flex e-con-boxed e-con e-child\" data-id=\"33ee95de\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1cfb1e62 e-con-full e-flex e-con e-child\" data-id=\"1cfb1e62\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-253c1cdc elementor-headline--style-highlight elementor-widget elementor-widget-animated-headline\" data-id=\"253c1cdc\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;marker&quot;:&quot;underline&quot;,&quot;highlighted_text&quot;:&quot;La plateforme de pr\\u00e9vision &amp; d\\u2019analyse&quot;,&quot;highlight_animation_duration&quot;:0,&quot;headline_style&quot;:&quot;highlight&quot;}\" data-widget_type=\"animated-headline.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h1 class=\"elementor-headline\">\n\t\t\t\t\t<span class=\"elementor-headline-plain-text elementor-headline-text-wrapper\">Mirus Prognolite -  <br><\/span>\n\t\t\t\t<span class=\"elementor-headline-dynamic-wrapper elementor-headline-text-wrapper\">\n\t\t\t\t\t<span class=\"elementor-headline-dynamic-text elementor-headline-text-active\">La plateforme de pr\u00e9vision &amp; d\u2019analyse<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t\t<span class=\"elementor-headline-plain-text elementor-headline-text-wrapper\">pour l\u2019h\u00f4tellerie &amp; la restauration<\/span>\n\t\t\t\t\t<\/h1>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b71f8d4 e-flex e-con-boxed e-con e-parent\" data-id=\"b71f8d4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6a52352 e-flex e-con-boxed e-con e-child\" data-id=\"6a52352\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5780991 elementor-widget elementor-widget-heading\" data-id=\"5780991\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Des pr\u00e9visions pr\u00e9cises, de meilleures d\u00e9cisions\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7d69be8 elementor-widget elementor-widget-heading\" data-id=\"7d69be8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"> Pr\u00e9visions de chiffre d\u2019affaires et de personnel bas\u00e9es sur l\u2019IA pour votre entreprise\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9cc3f96 elementor-widget elementor-widget-text-editor\" data-id=\"9cc3f96\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400\"><strong>Mirus Prognolite<\/strong> est la solution intelligente qui r\u00e9volutionne votre <strong>planification du chiffre d\u2019affaires et du personnel<\/strong> dans l\u2019h\u00f4tellerie-restauration. Exploitez la puissance de l\u2019intelligence artificielle pour des <strong>pr\u00e9visions pr\u00e9cises du chiffre d\u2019affaires et de la fr\u00e9quentation<\/strong>. Optimisez ainsi vos effectifs, r\u00e9duisez le gaspillage alimentaire et am\u00e9liorez durablement votre rentabilit\u00e9 \u2013 pour des d\u00e9cisions strat\u00e9giques fond\u00e9es sur des faits fiables plut\u00f4t que sur l\u2019intuition.  <\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f55c482 e-con-full e-flex e-con e-child\" data-id=\"f55c482\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-87cc15d elementor-widget elementor-widget-button\" data-id=\"87cc15d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#form\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">D\u00e9couvrir Mirus Prognolite<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-285ad627 e-flex e-con-boxed e-con e-parent\" data-id=\"285ad627\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-4296dcc6 e-con-full e-flex e-con e-child\" data-id=\"4296dcc6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-108570ef e-con-full e-flex e-con e-child\" data-id=\"108570ef\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-758a52c4 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"758a52c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"58\" height=\"58\" viewBox=\"0 0 58 58\" fill=\"none\"><g id=\"video-call-2 1\" clip-path=\"url(#clip0_1447_4504)\"><path id=\"Vector\" d=\"M53.5141 6.35508H33.4746V5.39219C33.4746 2.92266 31.4695 0.90625 28.9887 0.90625C26.5078 0.90625 24.5027 2.91133 24.5027 5.39219V6.35508H4.48594C2.00508 6.35508 0 8.37148 0 10.841V43.534C0 46.0035 2.00508 48.0199 4.48594 48.0199H18.918L18.2949 51.7695H17.1961C15.7234 51.7695 14.534 52.9703 14.534 54.4316C14.534 55.893 15.7348 57.0938 17.1961 57.0938H40.8039C42.2766 57.0938 43.466 55.893 43.466 54.4316C43.466 52.9703 42.2652 51.7695 40.8039 51.7695H39.7051L39.082 48.0199H53.5141C55.9836 48.0199 58 46.0148 58 43.534V10.841C58 8.37148 55.9949 6.35508 53.5141 6.35508ZM26.2133 7.21602V5.40352C26.2133 3.87422 27.4594 2.6168 29 2.6168C30.5406 2.6168 31.7867 3.86289 31.7867 5.40352V10.0027H26.2246V7.22734L26.2133 7.21602ZM29.0566 11.6906V13.5598C29.0566 14.0242 29.4418 14.4094 29.9062 14.4094C30.3707 14.4094 30.7559 14.0242 30.7559 13.5598V11.6906H52.6645V26.3379H47.3629L44.4176 24.8652C44.3949 24.8652 44.3836 24.8312 44.3836 24.8086V23.5172C45.4824 22.7016 46.1961 21.3875 46.1961 19.9148V18.1023C46.1961 15.6328 44.191 13.6164 41.7102 13.6164C39.2293 13.6164 37.2469 15.6102 37.2242 18.057C37.2242 18.057 37.2242 18.0797 37.2242 18.091V19.9035C37.2242 21.3762 37.9379 22.6902 39.0367 23.5059V24.8312L36.0574 26.3266H30.7559V17.1848C30.7559 16.7203 30.3707 16.3352 29.9062 16.3352C29.4418 16.3352 29.0566 16.7203 29.0566 17.1848V42.673H26.2133V37.9379C26.2133 36.5785 25.4543 35.3551 24.2422 34.7434L21.3082 33.2707C20.9797 33.1008 20.7758 32.7723 20.7758 32.4098V30.5406C22.4184 29.4078 23.4945 27.5047 23.4945 25.3637V24.4688V23.5398C23.4945 21.3195 22.3391 19.3711 20.6059 18.2496C20.7078 17.9098 20.7645 17.5473 20.7645 17.1848C20.7645 15.2137 19.1559 13.6164 17.1961 13.6164C15.2363 13.6164 13.6277 15.225 13.6277 17.1848C13.6277 19.1445 13.6844 17.9098 13.7863 18.2496C12.0531 19.3711 10.8977 21.3195 10.8977 23.5398V25.3523C10.8977 27.4934 11.9738 29.3965 13.6164 30.5293V32.3984C13.6164 32.7723 13.4125 33.1008 13.084 33.2594L10.15 34.732C8.92656 35.3438 8.17891 36.5672 8.17891 37.9266V42.6617H5.33555V11.6906H29.068H29.0566ZM44.4062 41.2004C44.3836 41.2004 44.3723 41.1664 44.3723 41.1438V39.8523C45.4711 39.0367 46.1848 37.7227 46.1848 36.25V34.4375C46.1848 31.968 44.1797 29.9516 41.6988 29.9516C39.218 29.9516 37.2355 31.9453 37.2129 34.3922C37.2129 34.3922 37.2129 34.4148 37.2129 34.4262V36.2387C37.2129 37.7113 37.9266 39.0254 39.0254 39.841V41.1664L36.0348 42.6617H30.7332V28.0145H52.6418V42.6617H47.3402L44.3836 41.1891L44.4062 41.2004ZM43.568 42.6844H39.8523L40.2715 42.4805C40.5547 42.3332 40.7359 42.0387 40.7359 41.7215V40.6453C41.0531 40.7133 41.3703 40.7473 41.6988 40.7473C42.0273 40.7473 42.3559 40.7133 42.6617 40.6453V41.1551C42.6617 41.7895 43.0016 42.3672 43.5566 42.6844H43.568ZM41.7102 39.048C40.1809 39.048 38.9234 37.802 38.9234 36.2613V35.5023C40.1355 35.7516 42.2539 36.1141 44.4855 36.182V36.2613C44.4855 37.7906 43.2395 39.048 41.6988 39.048H41.7102ZM44.4969 34.4941C42.2426 34.4035 40.0902 34.0184 39.0141 33.7918C39.3086 32.5797 40.4074 31.6734 41.7215 31.6734C43.0355 31.6734 44.5082 32.9195 44.5082 34.4602V34.5055L44.4969 34.4941ZM38.9348 19.1559C40.1469 19.4051 42.2652 19.7676 44.4969 19.8355V19.9148C44.4969 21.4441 43.2508 22.7016 41.7102 22.7016C40.1695 22.7016 38.9234 21.4555 38.9234 19.9148V19.1559H38.9348ZM44.4969 18.1477C42.2426 18.057 40.0902 17.6719 39.0141 17.4453C39.3086 16.2332 40.4074 15.327 41.7215 15.327C43.0355 15.327 44.5082 16.573 44.5082 18.1137V18.159L44.4969 18.1477ZM43.568 26.3379H39.8637L40.2715 26.134C40.5547 25.9867 40.7359 25.6922 40.7359 25.375V24.2988C41.0531 24.3668 41.3703 24.4008 41.6988 24.4008C42.0273 24.4008 42.3559 24.3668 42.6617 24.2988V24.8086C42.6617 25.443 43.0016 26.0207 43.5566 26.3379H43.568ZM12.4609 38.493L10.5352 36.5672C10.5352 36.5672 10.5125 36.5445 10.5012 36.5445C10.6258 36.4426 10.7617 36.3406 10.909 36.2727L13.843 34.8C13.9902 34.7207 14.1375 34.6301 14.2621 34.5395L16.3352 36.6125V42.673H13.4918V41.0191C13.4918 40.0676 13.118 39.1613 12.4496 38.493H12.4609ZM11.8039 41.0305V42.6844H9.8668V38.323L11.2488 39.7051C11.6 40.0563 11.7926 40.532 11.7926 41.0305H11.8039ZM17.1961 18.952C19.7336 18.952 21.7953 21.0137 21.7953 23.5512V23.857C18.2609 24.9445 16.1539 22.2484 16.0633 22.1352C15.916 21.9426 15.6895 21.818 15.4402 21.7953C15.191 21.7727 14.9531 21.8633 14.7832 22.0445C13.9676 22.8602 13.1746 23.2453 12.6082 23.4379C12.6762 20.957 14.7039 18.952 17.2074 18.952H17.1961ZM15.3156 17.1961C15.3156 16.1652 16.1539 15.327 17.1848 15.327C18.2156 15.327 19.0539 16.1652 19.0539 17.1961C19.0539 18.227 19.0539 17.4227 19.0199 17.5359C18.4309 17.3547 17.8191 17.2641 17.1734 17.2641C16.5277 17.2641 15.916 17.366 15.327 17.5359C15.3043 17.4227 15.293 17.3207 15.293 17.2074L15.3156 17.1961ZM15.327 23.8344C15.7008 24.1855 16.2332 24.616 16.9016 24.9785C17.6945 25.409 18.8047 25.8168 20.1527 25.8168C21.5008 25.8168 21.2176 25.7602 21.7953 25.6242C21.6594 28.0484 19.6543 29.9742 17.2074 29.9742C14.7605 29.9742 12.6082 27.9125 12.6082 25.375V25.1937C13.2879 25.0352 14.2848 24.6727 15.3383 23.8344H15.327ZM15.2363 33.1008C15.293 32.8855 15.327 32.6477 15.327 32.4211V31.3789C15.916 31.5602 16.5504 31.6621 17.1961 31.6621C17.8418 31.6621 18.4762 31.5602 19.0652 31.3789V32.4211C19.0652 32.659 19.0992 32.8855 19.1559 33.1008L17.1961 35.0605L15.2363 33.1008ZM18.0457 36.6125L20.1188 34.5395C20.2547 34.6414 20.3906 34.732 20.5379 34.8L23.4719 36.2727C23.6191 36.352 23.7551 36.4426 23.8797 36.5445C23.8797 36.5445 23.857 36.5559 23.8457 36.5672L21.9199 38.493C21.2402 39.1727 20.8777 40.0676 20.8777 41.0191V42.673H18.0344V36.6125H18.0457ZM22.5883 41.0305C22.5883 40.532 22.7809 40.0563 23.132 39.7051L24.5141 38.323V42.6844H22.577V41.0305H22.5883ZM40.8039 53.4574C41.3363 53.4574 41.7668 53.8879 41.7668 54.4203C41.7668 54.9527 41.3363 55.3832 40.8039 55.3832H17.1961C16.6637 55.3832 16.2332 54.9527 16.2332 54.4203C16.2332 53.8879 16.6637 53.4574 17.1961 53.4574H19.0086H33.5312C33.9957 53.4574 34.3809 53.0723 34.3809 52.6078C34.3809 52.1434 33.9957 51.7582 33.5312 51.7582H20.0055L20.6285 48.0086H37.3488L37.9719 51.7582H37.1562C36.6918 51.7582 36.3066 52.1434 36.3066 52.6078C36.3066 53.0723 36.6918 53.4574 37.1562 53.4574H38.9688H40.7812H40.8039ZM53.5141 46.3094H4.48594C2.95664 46.3094 1.69922 45.0633 1.69922 43.5227V10.841C1.69922 9.31172 2.94531 8.0543 4.48594 8.0543H24.5254V9.99141H4.48594C4.02148 9.99141 3.63633 10.3766 3.63633 10.841V43.534C3.63633 43.9984 4.02148 44.3836 4.48594 44.3836H53.5254C53.9898 44.3836 54.375 43.9984 54.375 43.534V10.841C54.375 10.3766 53.9898 9.99141 53.5254 9.99141H33.4859V8.0543H53.5254C55.0547 8.0543 56.3121 9.30039 56.3121 10.841V43.534C56.3121 45.0633 55.066 46.3207 53.5254 46.3207L53.5141 46.3094Z\" fill=\"white\"><\/path><path id=\"Vector_2\" d=\"M29.0113 4.5426C28.5469 4.5426 28.1617 4.92776 28.1617 5.39221C28.1617 5.85667 28.5469 6.24182 29.0113 6.24182C29.4758 6.24182 29.8609 5.85667 29.8609 5.39221C29.8609 4.92776 29.4758 4.5426 29.0113 4.5426Z\" fill=\"white\"><\/path><\/g><defs><clipPath id=\"clip0_1447_4504\"><rect width=\"58\" height=\"58\" fill=\"white\"><\/rect><\/clipPath><\/defs><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4857a4bb elementor-widget elementor-widget-heading\" data-id=\"4857a4bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Pr\u00e9visions de chiffre d\u2019affaires bas\u00e9es sur l\u2019IA\n\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-38b0f3b3 elementor-widget elementor-widget-text-editor\" data-id=\"38b0f3b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Gr\u00e2ce \u00e0 une m\u00e9thode d\u2019apprentissage bas\u00e9e sur les donn\u00e9es, l\u2019IA analyse les exp\u00e9riences pass\u00e9es afin de permettre des pr\u00e9visions de chiffre d\u2019affaires fiables pour l\u2019avenir.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-22bfff12 e-con-full e-flex e-con e-child\" data-id=\"22bfff12\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-23318a40 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"23318a40\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"58\" height=\"58\" viewBox=\"0 0 58 58\" fill=\"none\"><g id=\"employee-2 1\"><path id=\"Vector\" d=\"M29.3625 17.1168C29.5664 16.3012 29.6797 15.4629 29.6797 14.6246C29.6797 10.9316 27.686 7.68047 24.6727 5.82266C24.65 2.60547 22.0219 0 18.8047 0C15.5875 0 12.9594 2.60547 12.9481 5.82266C9.93478 7.68047 7.94103 10.9316 7.94103 14.6246C7.94103 18.3176 8.04298 16.2898 8.25822 17.1055C7.55587 17.5699 7.11407 18.3855 7.11407 19.3031V19.9488C7.11407 21.1723 7.9297 22.2484 9.05118 22.509C9.28907 22.5656 9.53829 22.5883 9.77618 22.577C10.252 25.1258 11.7473 27.2555 13.7863 28.5922V30.0648C13.5711 30.0648 13.3672 30.1555 13.1973 30.3141L10.807 32.7043L6.44572 34.6074C4.24806 35.5703 2.83204 37.8246 2.934 40.2262L3.46642 52.6531C3.48908 53.1062 3.8629 53.4688 4.31603 53.4688C4.76915 53.4688 4.33868 53.4688 4.35001 53.4688C4.81447 53.4461 5.18829 53.0496 5.16564 52.5852L4.63322 40.1582C4.59923 39.3312 4.81447 38.527 5.23361 37.8359L7.61251 40.6906C8.36017 41.5855 8.76798 42.7184 8.76798 43.8852V52.6191C8.76798 53.0836 9.15314 53.4688 9.61759 53.4688C10.082 53.4688 10.4672 53.0836 10.4672 52.6191V43.8852C10.4672 42.3219 9.91212 40.8039 8.91525 39.6031L6.4004 36.5785C6.62697 36.4199 6.86486 36.284 7.1254 36.1707L10.9543 34.4941L13.6617 38.8781C13.9223 39.2973 14.3527 39.5805 14.8285 39.6598C14.9192 39.6711 14.9984 39.6824 15.0891 39.6824C15.4856 39.6824 15.8707 39.5465 16.1766 39.2746L17.9438 37.768V52.6191C17.9438 53.0836 18.3289 53.4688 18.7934 53.4688C19.2578 53.4688 19.643 53.0836 19.643 52.6191V37.768L21.4102 39.2746C21.716 39.5352 22.1012 39.6824 22.4977 39.6824C22.8942 39.6824 22.6676 39.6824 22.7582 39.6598C23.2453 39.5805 23.6758 39.2973 23.925 38.8781L27.0176 33.8598C27.2215 33.5199 27.1762 33.0895 26.893 32.8176L24.3895 30.3141C24.2309 30.1555 24.0156 30.0648 23.8004 30.0648V28.5922C25.8508 27.2555 27.3348 25.1145 27.8106 22.577C28.0485 22.5883 28.2977 22.577 28.5356 22.509C29.657 22.2484 30.4727 21.1609 30.4727 19.9488V19.3031C30.4727 18.4082 30.0195 17.5926 29.3172 17.1281L29.3625 17.1168ZM18.8047 1.69922C20.7758 1.69922 22.4297 3.08125 22.8602 4.92773C21.6027 4.44063 20.2434 4.16875 18.8047 4.16875C17.366 4.16875 16.0067 4.44063 14.7492 4.92773C15.1684 3.08125 16.8336 1.69922 18.8047 1.69922ZM15.1004 37.9605L12.3703 33.5312L13.7977 32.1039L17.5586 35.8648L15.1004 37.9605ZM18.8047 34.7094L15.4856 31.3902V29.4645C16.5164 29.8609 17.6379 30.0875 18.8047 30.0875C19.9715 30.0875 21.093 29.8609 22.1238 29.4645V31.3902L18.8047 34.7094ZM25.2391 33.5312L22.509 37.9605L20.0508 35.8648L23.8117 32.1039L25.2391 33.5312ZM28.8074 19.9375C28.8074 20.368 28.5356 20.7645 28.1731 20.8438C28.0938 20.8664 28.0031 20.8664 27.9238 20.8664C27.0856 20.8098 26.3152 21.4102 26.1567 22.2484C25.4996 25.8055 22.407 28.3883 18.7934 28.3883C15.1797 28.3883 12.0758 25.8055 11.4301 22.2598C11.2715 21.4215 10.5012 20.8211 9.6629 20.8777C9.58361 20.8777 9.50431 20.8777 9.41368 20.8551C9.05118 20.7645 8.77931 20.3793 8.77931 19.9488V19.3031C8.77931 18.8727 9.07384 18.4762 9.44767 18.4082C9.76486 18.3516 10.0594 18.4648 10.252 18.7141C10.4106 18.918 10.6258 19.0652 10.8637 19.1445C11.2149 19.2465 11.6 19.1898 11.9059 18.9746C12.5969 18.4875 13.186 17.8645 13.6504 17.1395C13.8996 16.743 13.7863 16.2219 13.3899 15.9613C12.9934 15.7121 12.4723 15.8254 12.2231 16.2219C11.9625 16.641 11.6453 17.0035 11.2828 17.3207C10.8977 16.9809 10.4106 16.7656 9.90079 16.709C9.71954 16.0293 9.62892 15.327 9.62892 14.6246C9.62892 9.79883 13.741 5.86797 18.7934 5.86797C23.8457 5.86797 27.9578 9.79883 27.9578 14.6246C27.9578 19.4504 27.8672 16.0293 27.6859 16.709C27.4367 16.7316 27.1762 16.7656 26.9496 16.8336L26.2586 16.2672C25.9301 15.9953 25.5223 15.8594 25.1031 15.882C24.3328 15.9273 22.3164 15.984 20.0281 15.4969C17.2074 14.8965 15.0438 13.7184 13.5938 11.9965C13.2879 11.634 12.7555 11.5887 12.393 11.8945C12.0305 12.2004 11.9852 12.7328 12.291 13.0953C13.9789 15.123 16.4711 16.4938 19.677 17.1734C22.1465 17.6945 24.3442 17.6379 25.1938 17.5926L26.2586 18.4648C26.5305 18.6914 26.9156 18.7254 27.2215 18.5441C27.3801 18.4535 27.9012 18.3742 28.1277 18.4195C28.5129 18.4988 28.7961 18.8727 28.7961 19.3031V19.9488L28.8074 19.9375Z\" fill=\"white\"><\/path><path id=\"Vector_2\" d=\"M51.4976 32.693H35.3777C34.4261 32.693 33.5199 33.0668 32.8515 33.7352L30.2687 36.318H29.7136C27.7425 36.318 26.1453 37.9266 26.1453 39.8864V54.4203C26.1453 56.3914 27.7539 57.9887 29.7136 57.9887H51.5089C53.48 57.9887 55.0773 56.3801 55.0773 54.4203V36.2614C55.0773 34.2903 53.4687 32.693 51.5089 32.693H51.4976ZM39.4898 34.936C39.841 34.5848 40.3167 34.3922 40.8152 34.3922H43.0808L41.4269 36.0461C41.2457 36.2274 40.9964 36.3293 40.7472 36.3293H38.0964L39.4785 34.9473L39.4898 34.936ZM34.041 34.936C34.3921 34.5848 34.8679 34.3922 35.3664 34.3922H37.632L35.6949 36.3293H32.6476L34.0296 34.9473L34.041 34.936ZM53.3667 54.4317C53.3667 55.4625 52.5285 56.3008 51.4976 56.3008H29.7023C28.6714 56.3008 27.8332 55.4625 27.8332 54.4317V39.8977C27.8332 38.8668 28.6714 38.0285 29.7023 38.0285H40.7585C41.4722 38.0285 42.1406 37.7567 42.639 37.2469L44.9386 34.9473C45.2898 34.5961 45.7656 34.4035 46.264 34.4035H51.4976C52.5285 34.4035 53.3667 35.2418 53.3667 36.2727V54.4317Z\" fill=\"white\"><\/path><path id=\"Vector_3\" d=\"M38.7875 39.9543C38.323 39.9543 37.9378 40.3394 37.9378 40.8039C37.9378 41.2683 38.323 41.6535 38.7875 41.6535C39.2519 41.6535 38.8441 41.6762 38.8441 41.7101V43.5226C38.8441 43.5566 38.8214 43.5793 38.7875 43.5793H31.5261C31.4921 43.5793 31.4695 43.5566 31.4695 43.5226V41.7101C31.4695 41.6762 31.4921 41.6535 31.5261 41.6535H35.1625C35.6269 41.6535 36.0121 41.2683 36.0121 40.8039C36.0121 40.3394 35.6269 39.9543 35.1625 39.9543H31.5261C30.5519 39.9543 29.7703 40.7473 29.7703 41.7101V43.5226C29.7703 44.4969 30.5632 45.2785 31.5261 45.2785H38.7875C39.7617 45.2785 40.5433 44.4855 40.5433 43.5226V41.7101C40.5433 40.7359 39.7503 39.9543 38.7875 39.9543Z\" fill=\"white\"><\/path><\/g><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a27ecf7 elementor-widget elementor-widget-heading\" data-id=\"4a27ecf7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Planification optimale des collaborateurs\n\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-19bc5888 elementor-widget elementor-widget-text-editor\" data-id=\"19bc5888\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400\">D\u00e9ployez votre \u00e9quipe de mani\u00e8re cibl\u00e9e et selon les besoins. Avec Mirus, vous pouvez visualiser l\u2019effectif optimal n\u00e9cessaire afin de r\u00e9duire les sureffectifs ou les sous-effectifs. <\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5523d58c e-con-full e-flex e-con e-child\" data-id=\"5523d58c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4336eea1 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"4336eea1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"58\" height=\"58\" viewBox=\"0 0 58 58\" fill=\"none\"><g id=\"woman 1\" clip-path=\"url(#clip0_1538_5940)\"><path id=\"Vector\" d=\"M31.1636 39.1387L26.757 37.2129L25.1144 35.8648L27.38 35.4117C28.1503 35.2531 28.7281 34.5961 28.7847 33.8144L29.2945 26.7344C30.0308 26.2699 30.5179 25.4203 30.5179 24.4801V23.8344C30.5179 23.064 30.1894 22.3504 29.6456 21.8746L29.7816 19.9601C29.9968 16.8789 28.966 13.9449 26.8589 11.6793C24.7519 9.42499 21.8972 8.17889 18.816 8.17889C15.7347 8.17889 12.8687 9.42499 10.773 11.6793C8.66596 13.9336 7.6351 16.8789 7.85033 19.9601L7.98627 21.8746C7.45385 22.3504 7.114 23.0641 7.114 23.857V24.5027C7.114 25.443 7.60111 26.2926 8.33744 26.757L8.8472 33.8371C8.90385 34.6187 9.48158 35.2758 10.2519 35.4344L12.5175 35.8875L10.8749 37.2355L6.4683 39.1613C4.27064 40.1242 2.85463 42.3785 2.95658 44.7801L3.489 57.207C3.51166 57.6601 3.88549 58.0226 4.33861 58.0226C4.79174 58.0226 4.36127 58.0226 4.3726 58.0226C4.83705 58 5.21088 57.6035 5.18822 57.1391L4.6558 44.7121C4.62181 43.8851 4.83705 43.0808 5.25619 42.3898L7.6351 45.2445C8.38275 46.1394 8.79056 47.2723 8.79056 48.4391V57.173C8.79056 57.6375 9.17572 58.0226 9.64017 58.0226C10.1046 58.0226 10.4898 57.6375 10.4898 57.173V48.4391C10.4898 46.8758 9.9347 45.3578 8.93783 44.157L6.42299 41.1324C6.64955 40.9738 6.88744 40.8379 7.14799 40.7246L10.9429 39.0707L11.7925 40.6226C12.2796 41.5062 13.1859 42.0047 14.1261 42.0047C15.0663 42.0047 14.9417 41.914 15.3269 41.7215L16.8449 40.9625L17.9777 42.0953V57.1844C17.9777 57.6488 18.3628 58.034 18.8273 58.034C19.2917 58.034 19.6769 57.6488 19.6769 57.1844V42.0953L20.8097 40.9625L22.3277 41.7215C22.7128 41.914 23.1206 42.0047 23.5285 42.0047C24.4687 42.0047 25.3749 41.5062 25.862 40.6226L26.7117 39.0707L30.5066 40.7246C30.7671 40.8379 31.005 40.9738 31.2316 41.1324L28.7167 44.157C27.7199 45.3578 27.1648 46.8758 27.1648 48.4391V57.173C27.1648 57.6375 27.5499 58.0226 28.0144 58.0226C28.4788 58.0226 28.864 57.6375 28.864 57.173V48.4391C28.864 47.2723 29.2718 46.1394 30.0195 45.2445L32.3984 42.3898C32.8175 43.0808 33.0328 43.8851 32.9988 44.7121L32.4663 57.1391C32.4437 57.6035 32.8062 58 33.282 58.0226C33.2933 58.0226 33.3046 58.0226 33.316 58.0226C33.7691 58.0226 34.1429 57.6601 34.1656 57.207L34.698 44.7801C34.7999 42.3785 33.3839 40.1242 31.1863 39.1613L31.1636 39.1387ZM27.0855 33.7012C27.0855 33.7238 27.0628 33.7465 27.0402 33.7578L23.823 34.4035V33.1348C25.4769 32.0586 26.7683 30.45 27.448 28.5355L27.0742 33.7125L27.0855 33.7012ZM9.67416 25.409C9.59486 25.409 9.51556 25.409 9.42494 25.3863C9.06244 25.2957 8.79056 24.9105 8.79056 24.4801V23.8344C8.79056 23.4039 9.0851 23.0074 9.45892 22.9394C9.77611 22.8828 10.0706 22.9961 10.2632 23.2453C10.4218 23.4492 10.637 23.5965 10.8749 23.6758C11.2261 23.7777 11.6226 23.7211 11.9171 23.5058C12.6081 23.0187 13.1972 22.3957 13.6617 21.6707C13.9109 21.2742 13.7976 20.7531 13.4011 20.4926C13.0046 20.2433 12.4835 20.3566 12.2343 20.7531C11.9738 21.1723 11.6566 21.5348 11.2941 21.8519C10.841 21.4555 10.2519 21.2289 9.64017 21.2289L9.53822 19.8242C9.35697 17.2187 10.2292 14.7379 12.0078 12.8234C13.7863 10.909 16.1992 9.86678 18.816 9.86678C21.4328 9.86678 23.8456 10.9203 25.6242 12.8234C27.4027 14.7379 28.2749 17.2187 28.0937 19.8242L27.9917 21.2289C27.6972 21.2289 27.3913 21.2629 27.0968 21.3308L25.9867 19.9941C25.6015 19.5297 24.9898 19.2918 24.3894 19.3711C23.6078 19.4844 21.546 19.7109 19.3484 19.4051C16.7656 19.0426 14.8398 18.0797 13.639 16.5504C13.3445 16.1766 12.812 16.1199 12.4495 16.4031C12.0757 16.6976 12.0191 17.2301 12.3023 17.5926C15.7234 21.9539 22.6109 21.3422 24.6386 21.0476C24.6499 21.0476 24.6726 21.0476 24.6839 21.0703L26.1679 22.8601C26.4285 23.1773 26.8929 23.2566 27.2441 23.0527C27.4027 22.9621 27.9238 22.8828 28.1503 22.9281C28.5355 23.0074 28.8187 23.3812 28.8187 23.8117V24.4574C28.8187 24.8879 28.5468 25.2844 28.1843 25.3637C28.105 25.3863 28.0144 25.3863 27.9351 25.3863C27.0968 25.3297 26.3265 25.9301 26.1679 26.7683C25.5109 30.3254 22.4183 32.9082 18.8046 32.9082C15.191 32.9082 12.087 30.3254 11.4413 26.7683C11.2828 25.9301 10.5124 25.3297 9.67416 25.3863V25.409ZM10.5691 33.7465C10.5464 33.7465 10.5238 33.7238 10.5238 33.6898L10.1499 28.5129C10.8296 30.4273 12.121 32.0359 13.7749 33.1121V34.3808L10.5578 33.7351L10.5691 33.7465ZM14.5453 40.1695C14.0808 40.4074 13.5144 40.2262 13.2652 39.773L12.3816 38.1644L13.2992 37.4168L15.5535 39.6711L14.5339 40.1808L14.5453 40.1695ZM18.8046 40.5094L15.1117 36.8164C15.3382 36.6578 15.4742 36.4086 15.4742 36.114V33.9957C16.505 34.4035 17.6265 34.6187 18.7933 34.6187C19.9601 34.6187 21.0816 34.3922 22.1124 33.9957V36.114C22.1124 36.4086 22.2597 36.6578 22.4749 36.8164L18.782 40.5094H18.8046ZM24.3554 39.773C24.1062 40.2262 23.5398 40.4074 23.0753 40.1695L22.0558 39.6598L24.3101 37.4055L25.2277 38.1531L24.3441 39.7617L24.3554 39.773Z\" fill=\"white\"><\/path><path id=\"Vector_2\" d=\"M39.6938 0C33.9731 0 28.7508 3.14922 26.0774 8.21289C25.8621 8.63203 26.0207 9.1418 26.4285 9.35703C26.8477 9.57227 27.3574 9.41367 27.5727 9.00586C29.9516 4.49727 34.5848 1.69922 39.6824 1.69922C47.227 1.69922 53.3668 7.83906 53.3668 15.3836C53.3668 22.9281 47.227 29.068 39.6824 29.068C32.1379 29.068 34.6074 28.3543 32.4438 26.9949C32.0473 26.7457 31.5262 26.8703 31.277 27.2668C31.0277 27.6633 31.1524 28.1844 31.5488 28.4336C33.9844 29.9629 36.8051 30.7672 39.6938 30.7672C48.1785 30.7672 55.0774 23.8684 55.0774 15.3836C55.0774 6.89883 48.1672 0 39.6938 0Z\" fill=\"white\"><\/path><path id=\"Vector_3\" d=\"M50.5915 14.534H42.22C41.8688 13.4805 40.8719 12.7215 39.6938 12.7215C38.5157 12.7215 38.8668 12.8234 38.5043 13.0047L33.9391 8.43944C33.6106 8.11093 33.0668 8.11093 32.7383 8.43944C32.4098 8.76796 32.4098 9.31171 32.7383 9.64022L37.3036 14.2055C37.1223 14.568 37.0204 14.9644 37.0204 15.3949C37.0204 16.8676 38.2211 18.057 39.6825 18.057C41.1438 18.057 41.8575 17.298 42.2086 16.2445H50.5801C51.0446 16.2445 51.4297 15.8594 51.4297 15.3949C51.4297 14.9305 51.0446 14.5453 50.5801 14.5453L50.5915 14.534ZM39.6938 16.3465C39.1614 16.3465 38.7309 15.916 38.7309 15.3836C38.7309 14.8512 39.1614 14.4207 39.6938 14.4207C40.2262 14.4207 40.6567 14.8512 40.6567 15.3836C40.6567 15.916 40.2262 16.3465 39.6938 16.3465Z\" fill=\"white\"><\/path><path id=\"Vector_4\" d=\"M39.6937 3.63635C39.2293 3.63635 38.8441 4.02151 38.8441 4.48596V6.29846C38.8441 6.76292 39.2293 7.14807 39.6937 7.14807C40.1582 7.14807 40.5433 6.76292 40.5433 6.29846V4.48596C40.5433 4.02151 40.1582 3.63635 39.6937 3.63635Z\" fill=\"white\"><\/path><path id=\"Vector_5\" d=\"M39.6937 23.6078C39.2293 23.6078 38.8441 23.9929 38.8441 24.4574V26.2699C38.8441 26.7344 39.2293 27.1195 39.6937 27.1195C40.1582 27.1195 40.5433 26.7344 40.5433 26.2699V24.4574C40.5433 23.9929 40.1582 23.6078 39.6937 23.6078Z\" fill=\"white\"><\/path><\/g><defs><clipPath id=\"clip0_1538_5940\"><rect width=\"58\" height=\"58\" fill=\"white\"><\/rect><\/clipPath><\/defs><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-40a2452d elementor-widget elementor-widget-heading\" data-id=\"40a2452d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Moins de gaspillage alimentaire\n\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7473cd82 elementor-widget elementor-widget-text-editor\" data-id=\"7473cd82\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400\">Minimisez le gaspillage alimentaire gr\u00e2ce \u00e0 des pr\u00e9visions pr\u00e9cises de la fr\u00e9quentation et du chiffre d\u2019affaires \u2013 pour des processus de cuisine durables et \u00e9conomiques.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d2b8585 e-con-full e-flex e-con e-child\" data-id=\"d2b8585\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7b012979 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"7b012979\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"58\" height=\"58\" viewBox=\"0 0 58 58\" fill=\"none\"><g id=\"employee-3 1\"><path id=\"Vector\" d=\"M15.191 43.7832H11.8492C11.3848 43.7832 10.9996 44.1684 10.9996 44.6328C10.9996 45.0973 11.3848 45.4824 11.8492 45.4824H15.191C15.6555 45.4824 16.0407 45.0973 16.0407 44.6328C16.0407 44.1684 15.6555 43.7832 15.191 43.7832Z\" fill=\"white\"><\/path><path id=\"Vector_2\" d=\"M34.834 34.2223L29.9629 32.3418L27.482 29.8609C27.3235 29.7023 27.1082 29.6117 26.893 29.6117V27.584C28.0711 26.3379 28.9094 24.752 29.2379 22.9621C29.4531 22.9734 29.6684 22.9621 29.8836 22.9168C31.0504 22.6789 31.9 21.5914 31.9 20.334V19.6883C31.9 18.952 31.5942 18.2836 31.107 17.7965C31.9 13.5031 31.2656 10.0141 29.2379 7.68047C27.2895 5.42618 24.1516 4.35 20.1527 4.56524C16.4258 4.76915 14.0356 6.49102 13.3106 7.10274C12.2797 7.23868 9.33439 7.98633 9.33439 12.0984C9.33439 16.2106 9.70822 16.2785 9.96876 17.3207C9.0965 17.7285 8.50743 18.6461 8.50743 19.6883V20.334C8.50743 21.5914 9.35704 22.6676 10.5238 22.9168C10.7391 22.9621 10.9543 22.9734 11.1695 22.9621C11.4981 24.752 12.3363 26.3379 13.5145 27.584V29.6117C13.2992 29.6117 13.0953 29.7023 12.9254 29.8609L10.4445 32.3418L5.57345 34.2223C3.22853 35.1285 1.72189 37.4168 1.82384 39.9203L2.51486 57.1844C2.53751 57.6375 2.91134 58 3.36447 58C3.81759 58 3.38712 58 3.39845 58C3.8629 57.9773 4.23673 57.5809 4.21408 57.1164L3.52306 39.8523C3.5004 39.3992 3.55704 38.9461 3.68165 38.5156L6.44572 41.2797C7.22736 42.0613 7.66915 43.1148 7.66915 44.225V57.1504C7.66915 57.6148 8.05431 58 8.51876 58C8.98322 58 9.36837 57.6148 9.36837 57.1504V44.225C9.36837 42.6617 8.75665 41.1891 7.65783 40.0789L4.54259 36.9637C4.98439 36.4539 5.53947 36.0574 6.1965 35.8082L10.7391 34.0523L14.2055 39.252C14.6246 39.8863 15.3043 40.2828 16.052 40.3621C16.1313 40.3621 16.2219 40.3734 16.3012 40.3734C16.7656 40.3734 17.2188 40.2488 17.6039 40.0109L16.8563 57.1164C16.8336 57.5809 17.1961 57.9773 17.6719 58C17.6832 58 17.6945 58 17.7059 58C18.159 58 18.5328 57.6488 18.5555 57.1844L19.2465 41.325H21.1723L21.8633 57.1844C21.886 57.6375 22.2598 58 22.7129 58C23.166 58 22.7356 58 22.7469 58C23.2113 57.9773 23.5738 57.5809 23.5625 57.1164L22.8149 40.0109C23.2113 40.2488 23.6531 40.3734 24.1176 40.3734C24.582 40.3734 24.2875 40.3734 24.3668 40.3621C25.1258 40.2828 25.7942 39.8863 26.2133 39.252L29.6797 34.0523L34.2223 35.8082C34.8793 36.0574 35.4344 36.4652 35.8762 36.9637L32.761 40.0789C31.6508 41.1891 31.0504 42.6617 31.0504 44.225V57.1504C31.0504 57.6148 31.4356 58 31.9 58C32.3645 58 32.7496 57.6148 32.7496 57.1504V44.225C32.7496 43.1148 33.1801 42.0727 33.9731 41.2797L36.7371 38.5156C36.8617 38.9348 36.9184 39.3879 36.8957 39.8523L36.2047 57.1164C36.182 57.5809 36.5559 57.9773 37.0203 58C37.0317 58 37.043 58 37.0543 58C37.5074 58 37.8813 57.6375 37.9039 57.1844L38.5949 39.9203C38.6969 37.4168 37.1903 35.1172 34.8453 34.2223H34.834ZM12.8348 22.6449C12.6762 21.8066 11.9059 21.2063 11.0676 21.2629C10.9996 21.2629 10.9203 21.2629 10.8524 21.2516C10.4785 21.1723 10.1953 20.7871 10.1953 20.334V19.6883C10.1953 19.2578 10.4899 18.8613 10.8637 18.7934C11.1809 18.7367 11.4754 18.85 11.668 19.0992C11.8266 19.3031 12.0418 19.4504 12.2797 19.5297C12.6309 19.6316 13.0274 19.575 13.3219 19.3598C14.0129 18.8727 14.602 18.2496 15.0664 17.5246C15.3156 17.1281 15.2024 16.607 14.8059 16.3465C14.4094 16.0973 13.8883 16.2106 13.6391 16.607C13.3785 17.0262 13.0613 17.3887 12.6988 17.7059C12.4043 17.4566 12.0645 17.2641 11.702 17.1734C11.4754 16.3125 11.0563 14.3981 11.0563 12.0871C11.0563 9.77618 11.4867 9.73086 12.3363 9.19844C12.9934 8.7793 13.6957 8.76797 13.6957 8.76797C13.911 8.76797 14.1262 8.67735 14.2848 8.53008C14.3074 8.50743 16.4711 6.46836 20.2774 6.26446C23.7324 6.08321 26.3945 6.95547 27.9918 8.79063C29.6004 10.6484 30.1328 13.5145 29.5438 17.0941C29.2832 17.0828 29 17.0941 28.7281 17.1508L27.8785 15.1004C27.7199 14.7039 27.2895 14.5 26.8817 14.602C26.8024 14.6246 18.5328 16.7203 15.0551 12.393C14.7606 12.0305 14.2281 11.9738 13.8656 12.257C13.5031 12.5516 13.4465 13.084 13.7297 13.4465C17.2641 17.8418 24.2988 16.8563 26.5871 16.3918L27.2442 17.9777C27.516 18.6234 28.207 18.9859 28.8867 18.816C29.1586 18.7481 29.4418 18.7367 29.5777 18.7707C29.9629 18.85 30.2461 19.2238 30.2461 19.6543V20.3C30.2461 20.7418 29.9629 21.1383 29.5891 21.2176C29.5098 21.2289 29.4418 21.2402 29.3738 21.2289C28.5356 21.1723 27.7652 21.7727 27.6067 22.6109C26.9496 26.168 23.857 28.7508 20.2434 28.7508C16.6297 28.7508 13.5258 26.168 12.8801 22.6109L12.8348 22.6449ZM16.8676 38.4363C16.6977 38.6063 16.4485 38.6969 16.2106 38.6742C15.9613 38.6516 15.7461 38.5156 15.6102 38.3117L12.1211 33.0668L13.5711 31.6168L18.9633 36.3406L16.8676 38.4363ZM19.3031 39.6258L19.3598 38.3344L20.1981 37.4961L21.0363 38.3344L21.093 39.6258H19.3145H19.3031ZM20.1981 35.1738L15.2024 30.8012V29C16.6524 29.9402 18.3742 30.4727 20.1981 30.4727C22.0219 30.4727 23.7438 29.9289 25.1938 29V30.8012L20.1981 35.1738ZM24.7973 38.3117C24.6613 38.5156 24.4461 38.6516 24.1969 38.6742C24.0496 38.6856 23.7777 38.6742 23.5399 38.4363L21.4442 36.3406L26.8363 31.6168L28.2863 33.0668L24.7973 38.3117Z\" fill=\"white\"><\/path><path id=\"Vector_3\" d=\"M51.7016 1.8125H51.6449V0.849609C51.6449 0.385156 51.2598 0 50.7953 0C50.3309 0 49.9457 0.385156 49.9457 0.849609V1.8125H35.2985V0.849609C35.2985 0.385156 34.9133 0 34.4488 0C33.9844 0 33.5992 0.385156 33.5992 0.849609V1.8125H33.5426C31.866 1.8125 30.3367 2.74141 29.5664 4.23672C29.3512 4.65586 29.5098 5.16562 29.9289 5.38086C30.3481 5.59609 30.8578 5.4375 31.0731 5.01836C31.5488 4.08945 32.5004 3.51172 33.5426 3.51172H33.5992V4.47461C33.5992 4.93906 33.9844 5.32422 34.4488 5.32422C34.9133 5.32422 35.2985 4.93906 35.2985 4.47461V3.51172H49.9457V4.47461C49.9457 4.93906 50.3309 5.32422 50.7953 5.32422C51.2598 5.32422 51.6449 4.93906 51.6449 4.47461V3.51172H51.7016C53.2309 3.51172 54.4883 4.75781 54.4883 6.29844V6.35508H32.2965C31.832 6.35508 31.4469 6.74023 31.4469 7.20469C31.4469 7.66914 31.832 8.0543 32.2965 8.0543H54.4883V20.8211C54.4883 22.3504 53.2422 23.6078 51.7016 23.6078H33.5426C33.2594 23.6078 32.9875 23.5625 32.727 23.4832C32.2738 23.3473 31.7981 23.5965 31.6621 24.0496C31.5262 24.5027 31.7754 24.9785 32.2285 25.1145C32.659 25.2504 33.1008 25.307 33.5426 25.307H51.7016C54.1711 25.307 56.1875 23.302 56.1875 20.8211V6.29844C56.1875 3.82891 54.1824 1.8125 51.7016 1.8125Z\" fill=\"white\"><\/path><path id=\"Vector_4\" d=\"M44.4403 10.8976H40.804C40.3395 10.8976 39.9543 11.2828 39.9543 11.7473C39.9543 12.2117 40.3395 12.5969 40.804 12.5969H44.4403C44.9047 12.5969 45.2899 12.2117 45.2899 11.7473C45.2899 11.2828 44.9047 10.8976 44.4403 10.8976Z\" fill=\"white\"><\/path><path id=\"Vector_5\" d=\"M51.7015 10.8976H48.0652C47.6007 10.8976 47.2156 11.2828 47.2156 11.7473C47.2156 12.2117 47.6007 12.5969 48.0652 12.5969H51.7015C52.166 12.5969 52.5511 12.2117 52.5511 11.7473C52.5511 11.2828 52.166 10.8976 51.7015 10.8976Z\" fill=\"white\"><\/path><path id=\"Vector_6\" d=\"M37.1676 10.8976H34.4489C33.9844 10.8976 33.5992 11.2828 33.5992 11.7473C33.5992 12.2117 33.9844 12.5969 34.4489 12.5969H37.1676C37.6321 12.5969 38.0172 12.2117 38.0172 11.7473C38.0172 11.2828 37.6321 10.8976 37.1676 10.8976Z\" fill=\"white\"><\/path><path id=\"Vector_7\" d=\"M44.4403 14.534H40.804C40.3395 14.534 39.9543 14.9192 39.9543 15.3836C39.9543 15.8481 40.3395 16.2332 40.804 16.2332H44.4403C44.9047 16.2332 45.2899 15.8481 45.2899 15.3836C45.2899 14.9192 44.9047 14.534 44.4403 14.534Z\" fill=\"white\"><\/path><path id=\"Vector_8\" d=\"M51.7015 14.534H48.0652C47.6007 14.534 47.2156 14.9192 47.2156 15.3836C47.2156 15.8481 47.6007 16.2332 48.0652 16.2332H51.7015C52.166 16.2332 52.5511 15.8481 52.5511 15.3836C52.5511 14.9192 52.166 14.534 51.7015 14.534Z\" fill=\"white\"><\/path><path id=\"Vector_9\" d=\"M37.1676 14.534H34.4489C33.9844 14.534 33.5992 14.9192 33.5992 15.3836C33.5992 15.8481 33.9844 16.2332 34.4489 16.2332H37.1676C37.6321 16.2332 38.0172 15.8481 38.0172 15.3836C38.0172 14.9192 37.6321 14.534 37.1676 14.534Z\" fill=\"white\"><\/path><path id=\"Vector_10\" d=\"M44.4403 18.159H40.804C40.3395 18.159 39.9543 18.5442 39.9543 19.0086C39.9543 19.4731 40.3395 19.8582 40.804 19.8582H44.4403C44.9047 19.8582 45.2899 19.4731 45.2899 19.0086C45.2899 18.5442 44.9047 18.159 44.4403 18.159Z\" fill=\"white\"><\/path><path id=\"Vector_11\" d=\"M51.7015 18.159H48.0652C47.6007 18.159 47.2156 18.5442 47.2156 19.0086C47.2156 19.4731 47.6007 19.8582 48.0652 19.8582H51.7015C52.166 19.8582 52.5511 19.4731 52.5511 19.0086C52.5511 18.5442 52.166 18.159 51.7015 18.159Z\" fill=\"white\"><\/path><path id=\"Vector_12\" d=\"M37.1676 18.159H34.4489C33.9844 18.159 33.5992 18.5442 33.5992 19.0086C33.5992 19.4731 33.9844 19.8582 34.4489 19.8582H37.1676C37.6321 19.8582 38.0172 19.4731 38.0172 19.0086C38.0172 18.5442 37.6321 18.159 37.1676 18.159Z\" fill=\"white\"><\/path><\/g><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7ddd57e8 elementor-widget elementor-widget-heading\" data-id=\"7ddd57e8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Int\u00e9gration transparente des donn\u00e9es  <\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-21dca98c elementor-widget elementor-widget-text-editor\" data-id=\"21dca98c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400\">Les syst\u00e8mes de caisse et autres sources de donn\u00e9es peuvent \u00eatre connect\u00e9s de mani\u00e8re transparente. Toutes les informations pertinentes sont ainsi int\u00e9gr\u00e9es dans vos pr\u00e9visions. <\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e0c4a3a e-con-full e-flex e-con e-child\" data-id=\"e0c4a3a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4ae41f57 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"4ae41f57\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"58\" height=\"58\" viewBox=\"0 0 58 58\" fill=\"none\"><g id=\"employees 1\" clip-path=\"url(#clip0_1538_5985)\"><path id=\"Vector\" d=\"M35.6836 40.9739H32.5004C32.0359 40.9739 31.6508 41.359 31.6508 41.8235C31.6508 42.2879 32.0359 42.6731 32.5004 42.6731H35.6836C36.148 42.6731 36.5332 42.2879 36.5332 41.8235C36.5332 41.359 36.148 40.9739 35.6836 40.9739Z\" fill=\"white\"><\/path><path id=\"Vector_2\" d=\"M54.3977 31.8773L49.7758 30.0875L47.4195 27.7312C47.2723 27.584 47.0684 27.4933 46.8758 27.482V25.6015C47.9859 24.4121 48.7789 22.9168 49.0961 21.2289C49.3 21.2289 49.4926 21.2289 49.6965 21.1836C50.8293 20.957 51.6449 19.9035 51.6449 18.6914V18.0683C51.6449 17.366 51.3617 16.7203 50.8973 16.2558C51.6449 12.1777 51.0332 8.84724 49.1074 6.62693C47.2383 4.47459 44.2363 3.44373 40.4188 3.64763C36.8957 3.84021 34.6188 5.46013 33.8938 6.0492C33.4973 6.09451 32.8289 6.23045 32.1492 6.63826C31.209 7.20466 30.0762 8.39412 30.0762 10.841C30.0762 13.2879 30.416 14.7605 30.6652 15.7801C29.8383 16.1879 29.2832 17.0601 29.2832 18.057V18.6687C29.2832 19.8808 30.0988 20.9344 31.2316 21.1609C31.4242 21.2062 31.6281 21.2176 31.832 21.2062C32.1492 22.8941 32.9422 24.4008 34.0524 25.5789V27.4594C33.8484 27.4707 33.6559 27.55 33.5086 27.7086L31.1524 30.0648L26.5305 31.8547C26.134 32.0133 25.7488 32.2058 25.3977 32.4437C25.0125 32.7043 24.9106 33.2367 25.1711 33.6218C25.341 33.8597 25.6016 33.9957 25.8734 33.9957C26.1453 33.9957 26.202 33.9504 26.3492 33.8484C26.5984 33.6785 26.859 33.5426 27.1422 33.4293L31.4356 31.7754L34.7207 36.7031C35.1285 37.3148 35.7856 37.7 36.5106 37.7793C36.5899 37.7793 36.6691 37.7906 36.7484 37.7906C37.1676 37.7906 37.5867 37.6773 37.9492 37.4734L37.2469 53.4574C37.2242 53.9219 37.5867 54.3183 38.0625 54.341C38.0738 54.341 38.0852 54.341 38.0965 54.341C38.5496 54.341 38.9234 53.9898 38.9461 53.5254L39.6031 38.6969H41.3703L42.0274 53.5254C42.05 53.9785 42.4238 54.341 42.877 54.341C43.3301 54.341 42.8996 54.341 42.9109 54.341C43.3754 54.3183 43.7379 53.9219 43.7266 53.4574L43.0242 37.4734C43.3867 37.6773 43.7945 37.7906 44.225 37.7906C44.6555 37.7906 44.3836 37.7906 44.4629 37.7793C45.1879 37.7113 45.8449 37.3148 46.2527 36.7031L49.5379 31.7754L53.8313 33.4293C54.4317 33.6558 54.9527 34.0297 55.3606 34.4941L52.4266 37.4281C51.3617 38.4929 50.784 39.8976 50.784 41.4043V53.4801C50.784 53.9445 51.1691 54.3297 51.6336 54.3297C52.0981 54.3297 52.4832 53.9445 52.4832 53.4801V41.4043C52.4832 40.3621 52.891 39.3765 53.6274 38.6289L56.2102 36.0461C56.3121 36.4312 56.3574 36.8277 56.3461 37.2355L55.6891 53.4461C55.6664 53.9105 56.0402 54.307 56.5047 54.3297C56.516 54.3297 56.5274 54.3297 56.5387 54.3297C56.9918 54.3297 57.3656 53.9672 57.3883 53.514L58.0453 37.3035C58.1473 34.9019 56.6973 32.7043 54.4543 31.832L54.3977 31.8773ZM33.4859 20.8777C33.3387 20.0621 32.5797 19.473 31.7641 19.5297C31.6961 19.5297 31.6281 19.5297 31.5715 19.5183C31.2316 19.4504 30.9824 19.0879 30.9824 18.6914V18.0797C30.9824 17.6832 31.243 17.332 31.5828 17.2754C31.866 17.2301 32.1379 17.332 32.3078 17.5586C32.4664 17.7625 32.6703 17.9097 32.9082 17.9777C33.2594 18.0797 33.6445 18.023 33.9391 17.8078C34.4715 17.434 34.9359 16.9695 35.3324 16.4484C35.6156 16.0746 35.5363 15.5422 35.1625 15.259C34.7887 14.9758 34.2563 15.0551 33.9731 15.4289C33.7805 15.6894 33.5539 15.9273 33.316 16.1426C33.0441 15.916 32.727 15.7461 32.3984 15.6554C32.1832 14.8172 31.7867 13.0273 31.7867 10.8636C31.7867 8.69998 32.1832 8.64334 32.9762 8.1449C33.5879 7.74841 34.2449 7.73709 34.2449 7.73709C34.4602 7.73709 34.6754 7.64646 34.834 7.4992C34.8566 7.47654 36.941 5.53943 40.5207 5.34685C43.7945 5.1656 46.3207 5.99256 47.8274 7.73709C49.3453 9.49295 49.8551 12.189 49.3 15.5535C49.0734 15.5535 48.8242 15.5535 48.575 15.5988L47.782 13.6844C47.6234 13.2879 47.193 13.084 46.7852 13.1859C46.7059 13.2086 38.8555 15.191 35.5703 11.1015C35.2758 10.739 34.7434 10.6824 34.3809 10.9656C34.0184 11.2601 33.9617 11.7926 34.2563 12.1551C37.6207 16.3351 44.2816 15.4289 46.502 14.9871L47.1137 16.4711C47.3742 17.1054 48.0539 17.4566 48.7223 17.298C48.9942 17.2301 49.2547 17.2301 49.3567 17.2527C49.6965 17.3207 49.957 17.6605 49.957 18.0457V18.6687C49.957 19.0765 49.7078 19.4277 49.368 19.4957C49.3 19.507 49.232 19.5183 49.1754 19.507C48.3598 19.4504 47.6008 20.0394 47.4535 20.8551C46.8305 24.2195 43.9078 26.6664 40.4754 26.6664C37.0543 26.6664 34.1203 24.2195 33.4973 20.8551L33.4859 20.8777ZM37.2582 35.8988C37.043 36.114 36.7938 36.1254 36.6578 36.114C36.5332 36.1027 36.284 36.0461 36.1141 35.7855L32.8063 30.8238L34.1316 29.4984L39.2066 33.939L37.2469 35.8988H37.2582ZM39.6484 37.0203L39.7051 35.8535L40.4641 35.0945L41.2231 35.8535L41.2797 37.0203H39.6711H39.6484ZM40.4527 32.7722L35.7402 28.6488V27.0176C37.1109 27.8898 38.7309 28.3883 40.4527 28.3883C42.1746 28.3883 43.7945 27.8898 45.1652 27.0176V28.6488L40.4527 32.7722ZM44.8027 35.7855C44.6328 36.0347 44.3949 36.1027 44.259 36.114C44.1231 36.1254 43.8738 36.114 43.6586 35.8988L41.6988 33.939L46.7738 29.4984L48.0992 30.8238L44.7914 35.7855H44.8027Z\" fill=\"white\"><\/path><path id=\"Vector_3\" d=\"M26.9383 36.3293L22.7922 34.5168L20.5266 32.2512C20.3793 32.1039 20.1754 32.0133 19.9828 32.0019V30.6652C21.92 29.3965 23.336 27.3687 23.8004 24.9558C24.027 24.9558 24.2535 24.9445 24.4688 24.8879C25.5563 24.6273 26.3492 23.5851 26.3492 22.407V21.784C26.3492 20.923 25.9188 20.1527 25.2617 19.6996C25.4543 18.9293 25.5563 18.1363 25.5563 17.3433C25.5563 13.8203 23.6532 10.7277 20.7871 8.93787C20.7532 6.00388 18.2496 3.61365 15.1684 3.61365C12.0871 3.61365 9.58362 5.99255 9.54964 8.93787C6.68362 10.7164 4.7805 13.8203 4.7805 17.3433C4.7805 20.8664 4.88245 18.9179 5.07503 19.6883C4.418 20.1414 3.98753 20.923 3.98753 21.7953V22.407C3.98753 23.5851 4.7805 24.6273 5.868 24.8879C6.09456 24.9445 6.3098 24.9672 6.53636 24.9558C6.98948 27.3687 8.4055 29.3965 10.3539 30.6652V32.0019C10.15 32.0133 9.95745 32.0926 9.81019 32.2512L7.54456 34.5168L3.39847 36.3293C1.25745 37.2469 -0.0905956 39.4105 2.94265e-05 41.7215L0.498467 53.5593C0.521123 54.0125 0.894951 54.375 1.34808 54.375C1.8012 54.375 1.37073 54.375 1.38206 54.375C1.84651 54.3523 2.22034 53.9558 2.19769 53.4914L1.69925 41.6535C1.66526 40.8945 1.86917 40.1469 2.243 39.5125L4.47464 42.1859C5.17698 43.0355 5.56214 44.1004 5.56214 45.1992V53.514C5.56214 53.9785 5.94729 54.3636 6.41175 54.3636C6.8762 54.3636 7.26136 53.9785 7.26136 53.514V45.1992C7.26136 43.7039 6.72894 42.2426 5.77737 41.0984L3.4098 38.2551C3.6137 38.1191 3.82894 37.9945 4.0555 37.8926L7.66917 36.3179L10.2293 40.464C10.4785 40.8719 10.8977 41.1551 11.3735 41.223C11.4641 41.2344 11.5434 41.2457 11.634 41.2457C12.0192 41.2457 12.4043 41.1097 12.6989 40.8492L14.3188 39.4672V53.5254C14.3188 53.9898 14.7039 54.375 15.1684 54.375C15.6328 54.375 16.018 53.9898 16.018 53.5254V39.4672L17.6379 40.8492C17.9325 41.1097 18.3176 41.2457 18.7028 41.2457C19.0879 41.2457 18.8727 41.2457 18.9633 41.223C19.4391 41.1437 19.8582 40.8719 20.1075 40.464L22.6676 36.3179L26.2813 37.8926C26.5078 37.9945 26.7231 38.1191 26.927 38.2551L24.5594 41.0984C23.5965 42.2539 23.0754 43.7039 23.0754 45.1992V53.514C23.0754 53.9785 23.4606 54.3636 23.925 54.3636C24.3895 54.3636 24.7746 53.9785 24.7746 53.514V45.1992C24.7746 44.1004 25.1598 43.0242 25.8621 42.1859L28.0938 39.5125C28.4676 40.1469 28.6602 40.8945 28.6375 41.6535L28.1391 53.4914C28.1164 53.9558 28.4789 54.3523 28.9547 54.375C28.966 54.375 28.9774 54.375 28.9887 54.375C29.4418 54.375 29.8157 54.0125 29.8383 53.5593L30.3367 41.7215C30.4387 39.4218 29.0793 37.2582 26.9723 36.3293H26.9383ZM15.1571 5.33552C16.9696 5.33552 18.4875 6.49099 18.9407 8.05427C17.7625 7.61248 16.4938 7.36326 15.1571 7.36326C13.8203 7.36326 12.5516 7.60115 11.3735 8.05427C11.8266 6.49099 13.3446 5.33552 15.1571 5.33552ZM8.17894 24.6047C8.03167 23.789 7.27269 23.2 6.45706 23.2566C6.38909 23.2566 6.30979 23.2566 6.2305 23.234C5.90198 23.1547 5.66409 22.8035 5.66409 22.407V21.7953C5.66409 21.3988 5.92464 21.0476 6.26448 20.991C6.54769 20.9457 6.81956 21.0476 6.98948 21.2742C7.14808 21.4781 7.35198 21.6254 7.58987 21.6933C7.94104 21.7953 8.3262 21.7386 8.62073 21.5234C9.14183 21.1496 9.60628 20.7078 9.99144 20.1867C10.2746 19.8129 10.1953 19.2804 9.82151 18.9972C9.44769 18.714 8.91526 18.7933 8.63206 19.1672C8.43948 19.4277 8.22425 19.6543 7.98636 19.8695C7.62386 19.5636 7.18206 19.3597 6.70628 19.3031C6.54769 18.6687 6.45706 18.0117 6.45706 17.3547C6.45706 12.7781 10.3539 9.06248 15.1457 9.06248C19.9375 9.06248 23.8344 12.7781 23.8344 17.3547C23.8344 21.9312 23.7551 18.6687 23.5852 19.3031C23.3586 19.3258 23.1321 19.3597 22.9282 19.4164L22.2938 18.8953C21.9766 18.6347 21.5688 18.4988 21.161 18.5215C19.9149 18.6008 13.5145 18.7593 10.2407 14.8398C9.93479 14.4773 9.40237 14.432 9.03987 14.7379C8.67737 15.0437 8.63206 15.5761 8.93792 15.9386C10.5578 17.8758 12.9254 19.1898 15.9953 19.8355C18.3403 20.334 20.4246 20.2773 21.2403 20.232L22.2371 21.0476C22.509 21.2742 22.8942 21.3082 23.2 21.1269C23.3473 21.0476 23.8231 20.9683 24.0383 21.0136C24.3782 21.0816 24.6387 21.4215 24.6387 21.8066V22.4297C24.6387 22.8261 24.3895 23.1773 24.0723 23.2566C23.993 23.2793 23.925 23.2793 23.8457 23.2793C23.0301 23.2226 22.2711 23.8117 22.1239 24.6273C21.5008 27.9918 18.5782 30.4387 15.1457 30.4387C11.7133 30.4387 8.79065 27.9918 8.16761 24.6273L8.17894 24.6047ZM11.634 39.5125L9.07386 35.3664L10.3879 34.0523L13.911 37.5754L11.634 39.5125ZM15.1571 36.4199L12.0305 33.2933V31.5375C13.0047 31.9113 14.0582 32.1152 15.1571 32.1152C16.2559 32.1152 17.3094 31.9113 18.2836 31.5375V33.2933L15.1571 36.4199ZM18.6801 39.5125L16.4032 37.5754L19.9262 34.0523L21.2403 35.3664L18.6801 39.5125Z\" fill=\"white\"><\/path><path id=\"Vector_4\" d=\"M11.9739 44.7234H9.59497C9.13052 44.7234 8.74536 45.1085 8.74536 45.573C8.74536 46.0375 9.13052 46.4226 9.59497 46.4226H11.9852C12.4497 46.4226 12.8348 46.0375 12.8348 45.573C12.8348 45.1085 12.4497 44.7234 11.9852 44.7234H11.9739Z\" fill=\"white\"><\/path><\/g><defs><clipPath id=\"clip0_1538_5985\"><rect width=\"58\" height=\"58\" fill=\"white\"><\/rect><\/clipPath><\/defs><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d2c2637 elementor-widget elementor-widget-heading\" data-id=\"6d2c2637\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Utilisation simple et bas\u00e9e sur le web\n\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-56e2d8d6 elementor-widget elementor-widget-text-editor\" data-id=\"56e2d8d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400\">Planifiez et analysez ind\u00e9pendamment du lieu. La solution web est intuitive et toujours \u00e0 jour \u2013 m\u00eame pour plusieurs sites. <\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-757c2d1c e-con-full e-flex e-con e-child\" data-id=\"757c2d1c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-25307dfc elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"25307dfc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"58\" height=\"58\" viewBox=\"0 0 58 58\" fill=\"none\"><g id=\"add-user 1\"><path id=\"Vector\" d=\"M15.191 43.7832H11.8492C11.3848 43.7832 10.9996 44.1684 10.9996 44.6328C10.9996 45.0973 11.3848 45.4824 11.8492 45.4824H15.191C15.6555 45.4824 16.0407 45.0973 16.0407 44.6328C16.0407 44.1684 15.6555 43.7832 15.191 43.7832Z\" fill=\"white\"><\/path><path id=\"Vector_2\" d=\"M34.834 34.2222L29.9629 32.3417L27.482 29.8609C27.3235 29.7023 27.1082 29.6117 26.893 29.6117V27.5839C28.0711 26.3378 28.9094 24.7519 29.2379 22.9621C29.4531 22.9734 29.6684 22.9621 29.8836 22.9167C31.0504 22.6789 31.9 21.5914 31.9 20.3339V19.6882C31.9 18.9519 31.5942 18.2835 31.107 17.7964C31.9 13.5031 31.2656 10.014 29.2379 7.68041C27.2895 5.42612 24.1516 4.34994 20.1527 4.56518C16.4258 4.76908 14.0356 6.49096 13.3106 7.10268C12.2797 7.23862 9.33439 7.98627 9.33439 12.0984C9.33439 16.2105 9.70822 16.2785 9.96876 17.3206C9.0965 17.7285 8.50743 18.646 8.50743 19.6882V20.3339C8.50743 21.5914 9.35704 22.6675 10.5238 22.9167C10.7391 22.9621 10.9543 22.9734 11.1695 22.9621C11.4981 24.7519 12.3363 26.3378 13.5145 27.5839V29.6117C13.2992 29.6117 13.0953 29.7023 12.9254 29.8609L10.4445 32.3417L5.57345 34.2222C3.22853 35.1285 1.72189 37.4167 1.82384 39.9203L2.51486 57.1843C2.53751 57.6374 2.91134 57.9999 3.36447 57.9999C3.81759 57.9999 3.38712 57.9999 3.39845 57.9999C3.8629 57.9773 4.23673 57.5808 4.21408 57.1164L3.52306 39.8523C3.5004 39.3992 3.55704 38.946 3.68165 38.5156L6.44572 41.2796C7.22736 42.0613 7.66915 43.1148 7.66915 44.2249V57.1503C7.66915 57.6148 8.05431 57.9999 8.51876 57.9999C8.98322 57.9999 9.36837 57.6148 9.36837 57.1503V44.2249C9.36837 42.6617 8.75665 41.189 7.65783 40.0788L4.54259 36.9636C4.98439 36.4538 5.53947 36.0574 6.1965 35.8081L10.7391 34.0523L14.2055 39.2519C14.6246 39.8863 15.3043 40.2828 16.052 40.3621C16.1313 40.3621 16.2219 40.3734 16.3012 40.3734C16.7656 40.3734 17.2188 40.2488 17.6039 40.0109L16.8563 57.1164C16.8336 57.5808 17.1961 57.9773 17.6719 57.9999C17.6832 57.9999 17.6945 57.9999 17.7059 57.9999C18.159 57.9999 18.5328 57.6488 18.5555 57.1843L19.2465 41.3249H21.1723L21.8633 57.1843C21.886 57.6374 22.2598 57.9999 22.7129 57.9999C23.166 57.9999 22.7356 57.9999 22.7469 57.9999C23.2113 57.9773 23.5738 57.5808 23.5625 57.1164L22.8149 40.0109C23.2113 40.2488 23.6531 40.3734 24.1176 40.3734C24.582 40.3734 24.2875 40.3734 24.3668 40.3621C25.1258 40.2828 25.7942 39.8863 26.2133 39.2519L29.6797 34.0523L34.2223 35.8081C34.8793 36.0574 35.4344 36.4652 35.8762 36.9636L32.761 40.0788C31.6508 41.189 31.0504 42.6617 31.0504 44.2249V57.1503C31.0504 57.6148 31.4356 57.9999 31.9 57.9999C32.3645 57.9999 32.7496 57.6148 32.7496 57.1503V44.2249C32.7496 43.1148 33.1801 42.0726 33.9731 41.2796L36.7371 38.5156C36.8617 38.9347 36.9184 39.3878 36.8957 39.8523L36.2047 57.1164C36.182 57.5808 36.5559 57.9773 37.0203 57.9999C37.0317 57.9999 37.043 57.9999 37.0543 57.9999C37.5074 57.9999 37.8813 57.6374 37.9039 57.1843L38.5949 39.9203C38.6969 37.4167 37.1903 35.1171 34.8453 34.2222H34.834ZM12.8348 22.6449C12.6762 21.8066 11.9059 21.2062 11.0676 21.2628C10.9996 21.2628 10.9203 21.2628 10.8524 21.2515C10.4785 21.1722 10.1953 20.7871 10.1953 20.3339V19.6882C10.1953 19.2578 10.4899 18.8613 10.8637 18.7933C11.1809 18.7367 11.4754 18.8499 11.668 19.0992C11.8266 19.3031 12.0418 19.4503 12.2797 19.5296C12.6309 19.6316 13.0274 19.5749 13.3219 19.3597C14.0129 18.8726 14.602 18.2496 15.0664 17.5246C15.3156 17.1281 15.2024 16.607 14.8059 16.3464C14.4094 16.0972 13.8883 16.2105 13.6391 16.607C13.3785 17.0261 13.0613 17.3886 12.6988 17.7058C12.4043 17.4566 12.0645 17.264 11.702 17.1734C11.4754 16.3124 11.0563 14.398 11.0563 12.0871C11.0563 9.77612 11.4867 9.7308 12.3363 9.19838C12.9934 8.77924 13.6957 8.76791 13.6957 8.76791C13.911 8.76791 14.1262 8.67729 14.2848 8.53002C14.3074 8.50737 16.4711 6.4683 20.2774 6.2644C23.7324 6.08315 26.3945 6.95541 27.9918 8.79057C29.6004 10.6484 30.1328 13.5144 29.5438 17.0941C29.2832 17.0828 29 17.0941 28.7281 17.1507L27.8785 15.1003C27.7199 14.7038 27.2895 14.4999 26.8817 14.6019C26.8024 14.6246 18.5442 16.7316 15.0551 12.3929C14.7606 12.0304 14.2281 11.9738 13.8656 12.257C13.5031 12.5515 13.4465 13.0839 13.7297 13.4464C17.2641 17.8417 24.2988 16.8562 26.5871 16.3917L27.2442 17.9777C27.516 18.6234 28.207 18.9859 28.8867 18.816C29.1586 18.748 29.4418 18.7367 29.5777 18.7706C29.9629 18.8499 30.2461 19.2238 30.2461 19.6542V20.2999C30.2461 20.7417 29.9629 21.1382 29.5891 21.2175C29.5098 21.2288 29.4418 21.2402 29.3738 21.2288C28.5356 21.1722 27.7652 21.7726 27.6067 22.6109C26.9496 26.1679 23.857 28.7507 20.2434 28.7507C16.6297 28.7507 13.5258 26.1679 12.8801 22.6109L12.8348 22.6449ZM16.8676 38.4363C16.6977 38.6062 16.4485 38.6968 16.2106 38.6742C15.9613 38.6515 15.7461 38.5156 15.6102 38.3117L12.1211 33.0667L13.5711 31.6167L18.9633 36.3406L16.8676 38.4363ZM19.3145 39.6257L19.3711 38.3343L20.2094 37.496L21.0477 38.3343L21.1043 39.6257H19.3258H19.3145ZM20.2094 35.1738L15.2137 30.8011V28.9999C16.6637 29.9402 18.3856 30.4726 20.2094 30.4726C22.0332 30.4726 23.7551 29.9289 25.2051 28.9999V30.8011L20.2094 35.1738ZM24.7973 38.3117C24.6613 38.5156 24.4461 38.6515 24.1969 38.6742C23.9477 38.6968 23.7098 38.6175 23.5399 38.4363L21.4442 36.3406L26.8363 31.6167L28.2863 33.0667L24.7973 38.3117Z\" fill=\"white\"><\/path><path id=\"Vector_3\" d=\"M40.7925 0C36.7257 0 32.8855 1.57461 29.9855 4.44063C29.657 4.76914 29.6457 5.31289 29.9855 5.64141C30.314 5.96992 30.8578 5.98125 31.1863 5.64141C33.7691 3.09258 37.1789 1.68789 40.8039 1.68789C48.3484 1.68789 54.4882 7.82773 54.4882 15.3723C54.4882 22.9168 48.3484 29.0566 40.8039 29.0566C33.2593 29.0566 34.1656 27.8105 31.6507 25.5449C31.2996 25.2277 30.7672 25.2617 30.45 25.6129C30.1328 25.9641 30.1668 26.4965 30.5179 26.8137C33.35 29.3625 36.9976 30.7559 40.8039 30.7559C49.2886 30.7559 56.1875 23.857 56.1875 15.3723C56.1761 6.89883 49.2773 0 40.7925 0Z\" fill=\"white\"><\/path><path id=\"Vector_4\" d=\"M48.0653 14.534H41.6535V8.12231C41.6535 7.65786 41.2684 7.27271 40.8039 7.27271C40.3395 7.27271 39.9543 7.65786 39.9543 8.12231V14.534H34.4489C33.9844 14.534 33.5992 14.9192 33.5992 15.3836C33.5992 15.8481 33.9844 16.2333 34.4489 16.2333H39.9543V22.645C39.9543 23.1094 40.3395 23.4946 40.8039 23.4946C41.2684 23.4946 41.6535 23.1094 41.6535 22.645V16.2333H48.0653C48.5297 16.2333 48.9149 15.8481 48.9149 15.3836C48.9149 14.9192 48.5297 14.534 48.0653 14.534Z\" fill=\"white\"><\/path><\/g><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5450f65e elementor-widget elementor-widget-heading\" data-id=\"5450f65e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Base de d\u00e9cision fond\u00e9e\n\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6b6369e9 elementor-widget elementor-widget-text-editor\" data-id=\"6b6369e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400\">Fiez-vous \u00e0 des analyses bas\u00e9es sur des donn\u00e9es<\/span><span style=\"font-weight: 400\">. Mirus Prognolite vous fournit une base fiable pour les d\u00e9cisions strat\u00e9giques et op\u00e9rationnelles.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5beada8 e-flex e-con-boxed e-con e-parent\" data-id=\"5beada8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-9a026e9 e-con-full e-flex e-con e-child\" data-id=\"9a026e9\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-97ea98a e-con-full e-flex e-con e-child\" data-id=\"97ea98a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d79de1b elementor-widget elementor-widget-heading\" data-id=\"d79de1b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pr\u00e9visions bas\u00e9es sur l\u2019IA pour une s\u00e9curit\u00e9 de planification pr\u00e9cise\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9901fdb elementor-widget elementor-widget-text-editor\" data-id=\"9901fdb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400\">Misez sur des <strong>pr\u00e9visions de chiffre d\u2019affaires et de fr\u00e9quentation tr\u00e8s pr\u00e9cises<\/strong>, g\u00e9n\u00e9r\u00e9es par l\u2019intelligence artificielle \u00e0 partir de vos donn\u00e9es de caisse, PMS, m\u00e9t\u00e9orologiques et de vacances. <strong>Mirus Prognolite<\/strong> vous permet une <strong>planification pr\u00e9visionnelle des ressources<\/strong>, vous aide \u00e0 identifier rapidement les goulets d\u2019\u00e9tranglement et cr\u00e9e une base fiable pour des <strong>d\u00e9cisions strat\u00e9giques<\/strong> qui font progresser votre entreprise.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-17bbeab e-con-full e-flex e-con e-child\" data-id=\"17bbeab\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b9058e6 e-con-full e-flex e-con e-child\" data-id=\"b9058e6\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-e6efa69 e-con-full e-flex e-con e-child\" data-id=\"e6efa69\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4626b43 e-con-full e-flex e-con e-child\" data-id=\"4626b43\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-54b3c7e elementor-widget elementor-widget-heading\" data-id=\"54b3c7e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Planification id\u00e9ale du personnel pour une meilleure rentabilit\u00e9<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aed2157 elementor-widget elementor-widget-text-editor\" data-id=\"aed2157\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400\">Planifiez votre personnel <strong>en fonction des besoins<\/strong> et <strong>de mani\u00e8re rentable<\/strong>. Sur la base de pr\u00e9visions de chiffre d\u2019affaires intelligentes, <strong>Mirus Prognolite<\/strong> d\u00e9termine les besoins id\u00e9aux en collaborateurs pour chaque service, aide \u00e0 optimiser les co\u00fbts de personnel et \u00e0 \u00e9viter les sureffectifs ou les sous-effectifs co\u00fbteux. <strong>Augmentez la productivit\u00e9 et assurez la rentabilit\u00e9 de votre entreprise<\/strong> gr\u00e2ce \u00e0 une planification des d\u00e9ploiements bas\u00e9e sur les donn\u00e9es. <\/span><span style=\"font-weight: 400\"><br><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6a3de52 e-con-full e-flex e-con e-child\" data-id=\"6a3de52\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-89b0869 e-con-full e-flex e-con e-child\" data-id=\"89b0869\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7b164b3 elementor-widget elementor-widget-heading\" data-id=\"7b164b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Contr\u00f4le centralis\u00e9 gr\u00e2ce \u00e0 l\u2019int\u00e9gration transparente des donn\u00e9es\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-105c89c elementor-widget elementor-widget-text-editor\" data-id=\"105c89c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400\">Connectez vos <strong>syst\u00e8mes de caisse et de front-office<\/strong> directement \u00e0<strong> Mirus Prognolite<\/strong> \u2013 tous les indicateurs cl\u00e9s pertinents, tels que le chiffre d\u2019affaires, les heures des collaborateurs et la fr\u00e9quentation, sont regroup\u00e9s dans un <strong>tableau de bord intuitif<\/strong>. Les t\u00e2ches manuelles disparaissent enti\u00e8rement, ce qui vous permet d\u2019acc\u00e9der \u00e0 tout moment \u00e0 une <strong>base de donn\u00e9es fiable<\/strong> centralis\u00e9e et de piloter votre \u00e9tablissement de mani\u00e8re cibl\u00e9e. <\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ce11974 e-con-full e-flex e-con e-child\" data-id=\"ce11974\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-62d78d97 e-flex e-con-boxed e-con e-parent\" data-id=\"62d78d97\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-528c10ac elementor-widget elementor-widget-heading\" data-id=\"528c10ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pas encore convaincu ? Ne manquez pas ces avantages de Mirus Prognolite ! <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3cc429c8 e-con-full e-flex e-con e-child\" data-id=\"3cc429c8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-1b874472 e-con-full e-flex e-con e-child\" data-id=\"1b874472\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-45620855 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"45620855\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"58\" height=\"58\" viewBox=\"0 0 58 58\" fill=\"none\"><g id=\"key 1\"><path id=\"Vector\" d=\"M29.068 12.5176C19.9488 12.5176 12.5289 19.9148 12.5289 29.0227C12.5289 38.1305 19.9488 45.5277 29.068 45.5277C38.1871 45.5277 45.607 38.1305 45.607 29.0227C45.607 19.9148 38.1871 12.5176 29.068 12.5176ZM29.068 44.1684C20.6965 44.1684 13.8883 37.3715 13.8883 29.0227C13.8883 20.6738 20.6965 13.877 29.068 13.877C37.4394 13.877 44.2477 20.6738 44.2477 29.0227C44.2477 37.3715 37.4394 44.1684 29.068 44.1684Z\" fill=\"#005566\"><\/path><path id=\"Vector_2\" d=\"M56.2441 28.3202H51.2598C50.9086 16.6522 41.4609 7.18193 29.793 6.83076V1.82373C29.793 1.4499 29.4871 1.14404 29.1133 1.14404C28.7395 1.14404 28.4336 1.4499 28.4336 1.82373V6.83076C16.6523 7.18193 7.23867 16.6522 6.87617 28.3202H1.75586C1.38203 28.3202 1.07617 28.6261 1.07617 28.9999C1.07617 29.3737 1.38203 29.6796 1.75586 29.6796H6.87617C7.22734 41.3476 16.6523 50.8632 28.4336 51.2144V56.1761C28.4336 56.5499 28.7395 56.8558 29.1133 56.8558C29.4871 56.8558 29.793 56.5499 29.793 56.1761V51.2144C41.4609 50.8632 50.9086 41.3476 51.2598 29.6796H56.2441C56.618 29.6796 56.9238 29.3737 56.9238 28.9999C56.9238 28.6261 56.618 28.3202 56.2441 28.3202ZM29.068 49.8663C17.5699 49.8663 8.22422 40.5206 8.22422 29.0226C8.22422 17.5245 17.5699 8.17881 29.068 8.17881C40.566 8.17881 49.9117 17.5245 49.9117 29.0226C49.9117 40.5206 40.566 49.8663 29.068 49.8663Z\" fill=\"#005566\"><\/path><path id=\"Vector_3\" d=\"M35.0832 18.6234C33.418 16.9582 30.7219 16.9582 29.0566 18.6234L25.4203 22.2598C24.4574 23.2227 24.4574 24.7859 25.4203 25.7602L26.5078 26.8477L18.9859 34.3695C18.884 34.4715 18.816 34.6074 18.7933 34.7547L18.3515 37.8246C18.2949 38.1984 18.5555 38.5383 18.9293 38.5949C18.9633 38.5949 18.9973 38.5949 19.0199 38.5949C19.0426 38.5949 19.0539 38.5949 19.0652 38.5949L23.0187 38.3117C23.3473 38.2891 23.6078 38.0285 23.6418 37.7L23.857 35.627L25.9414 35.4004C26.3152 35.3664 26.5758 35.0266 26.5418 34.6641L26.3719 32.8289L26.9836 32.2172L28.6828 32.4098C28.898 32.4324 29.1019 32.3531 29.2492 32.2059L30.518 30.8691L31.6961 32.0473C32.659 33.0102 34.2223 33.0102 35.1965 32.0473L38.8328 28.4109C40.498 26.7457 40.498 24.0496 38.8328 22.3844L35.0719 18.6234H35.0832ZM28.5242 31.0164L26.8363 30.8238C26.6324 30.8012 26.4285 30.8691 26.2812 31.0164L25.2164 32.0813C25.0691 32.2285 25.0012 32.4211 25.0238 32.625L25.1598 34.109L23.1887 34.3242C22.8715 34.3582 22.6223 34.6074 22.5883 34.9359L22.373 36.9977L19.8242 37.1789L20.1074 35.1625L27.4707 27.7992L29.5777 29.9063L28.5129 31.0164H28.5242ZM37.8812 27.448L34.2449 31.0844C33.8144 31.5148 33.1008 31.5148 32.6703 31.0844L26.3719 24.7859C25.9414 24.3555 25.9414 23.6418 26.3719 23.2113L30.0082 19.575C31.141 18.4422 32.9875 18.4422 34.1203 19.575L37.8812 23.3359C39.014 24.4688 39.014 26.3152 37.8812 27.448Z\" fill=\"#005566\"><\/path><path id=\"Vector_4\" d=\"M33.2707 21.1948C32.5344 20.4585 31.3563 20.4585 30.6199 21.1948L29.793 22.0218C29.5324 22.2823 29.5324 22.7128 29.793 22.9847L34.4828 27.6745C34.7434 27.9351 35.1738 27.9351 35.4457 27.6745L36.2727 26.8476C37.009 26.1112 37.009 24.9331 36.2727 24.1968L33.2707 21.1948ZM35.3098 25.8847L34.9699 26.2245L31.243 22.4976L31.5828 22.1577C31.7867 21.9538 32.1152 21.9538 32.3078 22.1577L35.3098 25.1597C35.5137 25.3636 35.5137 25.6921 35.3098 25.8847Z\" fill=\"#005566\"><\/path><\/g><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1951ddbf elementor-widget elementor-widget-heading\" data-id=\"1951ddbf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">D\u00e9tection pr\u00e9coce des tendances\n\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3a4a971e elementor-widget elementor-widget-text-editor\" data-id=\"3a4a971e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400\">Gr\u00e2ce aux analyses de l\u2019IA, vous identifiez \u00e0 temps les fluctuations saisonni\u00e8res et les nouvelles tendances \u2013 pour une planification pr\u00e9visionnelle.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-72d1ae9b e-con-full e-flex e-con e-child\" data-id=\"72d1ae9b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-147dfa7e elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"147dfa7e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"58\" height=\"58\" viewBox=\"0 0 58 58\" fill=\"none\"><g id=\"folder 1\"><path id=\"Vector\" d=\"M8.83594 45.0632V43.7038C6.91016 43.7038 5.21094 42.0726 5.21094 40.0788V7.78232C5.21094 5.78857 6.86484 4.1913 8.86992 4.1913H20.5492C21.6367 4.1913 22.6676 4.66708 23.3586 5.50537L27.6746 10.7616H14.6699C11.9172 10.7616 9.64023 13.0159 9.64023 15.7686V44.3835C9.66289 44.7686 9.98008 45.0745 10.3652 45.0858H26.7004C27.2215 51.1804 32.591 55.7003 38.6855 55.1792C44.0551 54.7147 48.3145 50.4554 48.7789 45.0858H49.1414C51.9055 45.0745 54.1371 42.8429 54.1598 40.0788V15.7686C54.1484 13.0046 51.9055 10.7729 49.1414 10.7616H29.4305L24.4121 4.64443C23.4605 3.48896 22.0445 2.8206 20.5492 2.83193H8.86992C6.11719 2.83193 3.85156 5.04091 3.85156 7.78232V40.0788C3.86289 42.8315 6.0832 45.0518 8.83594 45.0632ZM37.734 53.8425C32.3645 53.8425 28.0145 49.4925 28.0145 44.1229C28.0145 38.7534 32.3645 34.4034 37.734 34.4034C43.1035 34.4034 47.4535 38.7534 47.4535 44.1229C47.4535 49.4925 43.1035 53.8311 37.734 53.8425ZM45.4258 36.1593C45.0859 35.8421 44.7461 35.5362 44.4062 35.2644V32.5569C44.4062 28.8979 41.3816 25.9186 37.7227 25.9186C34.0637 25.9186 31.0391 28.8979 31.0391 32.5569V35.2644C30.6992 35.5476 30.3594 35.8421 30.0195 36.1593V32.5569C30.0195 28.2976 33.4633 24.8538 37.7227 24.8538C41.982 24.8538 45.4258 28.2976 45.4258 32.5569V36.1593ZM43.0469 34.3808C39.7277 32.5909 35.7176 32.5909 32.3984 34.3808V32.5569C32.3984 29.6456 34.8113 27.278 37.7227 27.278C40.634 27.278 43.0469 29.6456 43.0469 32.5569V34.3808ZM52.7891 15.7686V40.0788C52.7777 42.0952 51.1465 43.7151 49.1301 43.7265H48.8016C48.7223 41.4608 48.0312 39.4444 46.7852 37.7452V32.5569C46.7852 27.5499 42.7297 23.4944 37.7227 23.4944C32.7156 23.4944 28.6602 27.5499 28.6602 32.5569V37.7452C27.5273 39.4444 26.7457 41.4608 26.6664 43.7265H10.9883V15.7686C10.9883 13.7749 12.6648 12.121 14.6586 12.121H49.1301C51.1352 12.121 52.7664 13.7522 52.7891 15.7686Z\" fill=\"#005566\"><\/path><path id=\"Vector_2\" d=\"M37.734 36.4993C33.5312 36.4993 30.1215 39.909 30.1215 44.1118C30.1215 48.3145 33.5312 51.7243 37.734 51.7243C41.9367 51.7243 45.3465 48.3145 45.3465 44.1118C45.3465 39.909 41.9367 36.4993 37.734 36.4993ZM37.734 50.3762C34.2789 50.3762 31.4809 47.5782 31.4809 44.1231C31.4809 40.668 34.2789 37.87 37.734 37.87C41.1891 37.87 43.9871 40.668 43.9871 44.1231C43.9871 47.5782 41.1891 50.3762 37.734 50.3762Z\" fill=\"#005566\"><\/path><path id=\"Vector_3\" d=\"M37.734 42.2085C36.7031 42.2085 35.8762 43.0468 35.8762 44.0663C35.8762 44.8253 36.3406 45.505 37.043 45.7882V46.6718C37.043 47.0456 37.3488 47.3515 37.7227 47.3515C38.0965 47.3515 38.4023 47.0456 38.4023 46.6718V45.7995C39.3539 45.4257 39.841 44.3608 39.4672 43.3979C39.1953 42.6843 38.5043 42.2085 37.734 42.2085ZM37.734 43.5679C38.0059 43.5679 38.2324 43.7831 38.2324 44.0663C38.2324 44.2929 38.0852 44.4854 37.8813 44.5421C37.7793 44.5194 37.6773 44.5194 37.5867 44.5421C37.3262 44.4628 37.1789 44.1796 37.2695 43.919C37.3375 43.7151 37.5301 43.5679 37.7453 43.5792L37.734 43.5679Z\" fill=\"#005566\"><\/path><\/g><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-36ce7168 elementor-widget elementor-widget-heading\" data-id=\"36ce7168\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Indicateurs cl\u00e9s quotidiens orient\u00e9s action\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45b7b531 elementor-widget elementor-widget-text-editor\" data-id=\"45b7b531\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400\">Recevez chaque jour des m\u00e9triques concr\u00e8tes que vous pouvez utiliser directement pour vos d\u00e9cisions op\u00e9rationnelles.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-488dcb74 e-con-full e-flex e-con e-child\" data-id=\"488dcb74\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1e88f3ce elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"1e88f3ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"58\" height=\"58\" viewBox=\"0 0 58 58\" fill=\"none\"><g id=\"hacker 1\"><path id=\"Vector\" d=\"M44.4062 11.5659C44.4062 11.3733 44.3156 11.2034 44.1684 11.0788C39.9316 7.48779 34.5621 5.5167 29 5.50537C16.0406 5.50537 5.50546 16.0405 5.50546 28.9999C5.50546 34.5507 7.48788 39.9315 11.0789 44.1683C11.2035 44.3155 11.3848 44.3948 11.566 44.4062H11.5887C11.7699 44.4062 11.9398 44.3382 12.0644 44.2022L44.2023 12.0757C44.3383 11.9397 44.4062 11.7585 44.4062 11.5659ZM21.4555 15.2815C21.4894 14.5679 22.1012 14.0128 22.8262 14.0581C22.9055 14.0581 22.9848 14.0694 23.0641 14.0921L26.5078 14.9304C28.1504 15.3269 29.8723 15.3269 31.5148 14.9304L34.9586 14.0921C35.6496 13.9222 36.3519 14.3526 36.5219 15.0437C36.5445 15.1229 36.5559 15.2022 36.5559 15.2815L36.6805 17.6718L28.6035 25.7487C26.7117 25.7147 24.8312 25.3976 23.0301 24.8085L20.9684 24.1628L21.4555 15.2702V15.2815ZM20.0621 25.3183L22.6109 26.1112C24.1289 26.6097 25.7035 26.9269 27.3008 27.0515L23.3473 31.005C20.334 30.6312 17.6605 29.9628 15.7801 29.1132C14.0129 28.3089 13.0047 27.3687 13.0047 26.519C13.0047 25.6694 13.6391 25.1144 14.7945 24.4347C15.984 23.7323 17.6719 23.1319 19.6883 22.6675L19.5863 24.6159C19.5637 24.9218 19.7676 25.205 20.0621 25.3069V25.3183ZM37.9719 16.3804L37.9039 15.2022C37.8246 13.7409 36.5672 12.6194 35.1059 12.6987C34.9473 12.6987 34.7773 12.7327 34.6187 12.7667L31.175 13.605C29.7363 13.9562 28.241 13.9562 26.8137 13.605L23.3699 12.7667C21.9426 12.4155 20.5039 13.2878 20.1641 14.7151C20.1301 14.8737 20.0961 15.0323 20.0961 15.2022L19.7676 21.2741C14.6019 22.373 11.6453 24.2874 11.6453 26.5304C11.6453 28.7733 12.2684 29.0112 15.2137 30.3593C17.0148 31.1862 19.3937 31.8206 22.1351 32.2171L11.634 42.7183C8.5414 38.8101 6.86484 33.9843 6.85351 28.9999C6.85351 16.7882 16.7883 6.86475 28.9887 6.86475C33.9617 6.86475 38.7988 8.55264 42.707 11.6452L37.9605 16.3917L37.9719 16.3804Z\" fill=\"#005566\"><\/path><path id=\"Vector_2\" d=\"M46.502 13.6616C46.3094 13.6616 46.1281 13.7296 45.9922 13.8655L35.0379 24.8198C34.9586 24.8765 34.8793 24.9444 34.834 25.0237L28.3316 31.5261L25.2617 34.6073C25.1711 34.6526 25.1031 34.7206 25.0352 34.7999C25.0238 34.8226 25.0012 34.8452 24.9898 34.8679L13.8883 45.9694C13.6277 46.23 13.6277 46.6604 13.8883 46.9323C13.8996 46.9437 13.9109 46.955 13.9336 46.9776C18.159 50.5233 23.5059 52.4831 29.0227 52.4831C41.982 52.4831 52.5172 41.948 52.5172 28.9886C52.5172 23.4718 50.5574 18.1249 47.0117 13.8995C46.8871 13.7522 46.7059 13.6616 46.5246 13.6616H46.502ZM35.7969 25.9866L37.9492 25.3183C38.2437 25.2276 38.4477 24.9444 38.425 24.6272L38.357 23.4265L38.9234 22.8601C42.6277 23.7776 44.9953 25.2276 44.9953 26.5644C44.9953 27.9011 43.3414 28.8753 40.5773 29.7702C37.8359 30.6651 34.2789 31.2089 30.45 31.3108L35.7855 25.9753L35.7969 25.9866ZM27.0289 39.4218C27.0289 41.914 25.0012 43.9417 22.509 43.9417C21.2742 43.9417 20.0848 43.4319 19.2352 42.537L25.6242 36.148C26.5191 36.9976 27.0289 38.187 27.0289 39.4218ZM29 51.1351C24.0496 51.1351 19.2465 49.4698 15.3609 46.4112L18.2723 43.4999C20.5266 45.8335 24.2422 45.9128 26.5871 43.6585C28.5355 41.778 28.9547 38.8214 27.5953 36.4765C28.6375 35.7628 29.4078 35.7741 30.4613 36.4991C28.8414 39.3312 29.827 42.9335 32.6477 44.5421C35.4797 46.162 39.082 45.1765 40.6906 42.3558C42.2992 39.5351 41.325 35.9214 38.5043 34.3128C36.1254 32.9534 33.1348 33.4065 31.2656 35.4116C29.691 34.3128 28.3543 34.3128 26.791 35.389C26.723 35.321 26.6551 35.253 26.5871 35.1851L29.0793 32.6929C33.5766 32.6929 37.8133 32.1038 41.0078 31.0616C45.4258 29.6116 46.3547 27.8104 46.3547 26.553C46.3547 24.5706 44.123 22.8714 40.0336 21.7272L46.4227 15.3382C49.4812 19.2351 51.1352 24.0382 51.1465 28.9772C51.1465 41.189 41.2117 51.1124 29.0113 51.1124L29 51.1351ZM35.559 34.9019C38.0512 34.9019 40.0789 36.9296 40.0789 39.4218C40.0789 41.914 38.0512 43.9417 35.559 43.9417C33.0668 43.9417 31.0391 41.914 31.0391 39.4218C31.0391 36.9296 33.0668 34.9019 35.559 34.9019Z\" fill=\"#005566\"><\/path><path id=\"Vector_3\" d=\"M29 1.61987C13.8996 1.61987 1.61993 13.8996 1.61993 29C1.61993 44.1003 13.8996 56.38 29 56.38C44.1004 56.38 56.3801 44.1003 56.3801 29C56.3801 13.8996 44.1004 1.61987 29 1.61987ZM29 55.032C14.6473 55.032 2.97931 43.3527 2.97931 29C2.97931 14.6472 14.6473 2.97925 29 2.97925C43.3527 2.97925 55.0207 14.6585 55.0207 29C55.0207 43.3414 43.3414 55.0207 29 55.0207V55.032Z\" fill=\"#005566\"><\/path><\/g><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-706b771 elementor-widget elementor-widget-heading\" data-id=\"706b771\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Moins d\u2019administration\n\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1e2c9760 elementor-widget elementor-widget-text-editor\" data-id=\"1e2c9760\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400\">Les processus num\u00e9ris\u00e9s soulagent votre \u00e9quipe et lib\u00e8rent du temps pour vos clients.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3aac5069 e-con-full e-flex e-con e-child\" data-id=\"3aac5069\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6ff72818 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"6ff72818\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"58\" height=\"58\" viewBox=\"0 0 58 58\" fill=\"none\"><g id=\"internet 1\" clip-path=\"url(#clip0_1447_4853)\"><path id=\"Vector\" d=\"M29 11.5889C19.4051 11.5889 11.5887 19.3939 11.5887 29.0002C11.5887 38.6064 19.3937 46.4115 29 46.4115C38.6062 46.4115 46.4113 38.6064 46.4113 29.0002C46.4113 19.3939 38.6062 11.5889 29 11.5889ZM38.1531 36.2049C38.8215 34.0865 39.1727 31.8889 39.218 29.6799H45.0293C44.8934 33.067 43.6699 36.3295 41.5516 38.9803C40.5434 37.9154 39.3879 36.9865 38.1418 36.2049H38.1531ZM16.4371 38.9803C14.3187 36.3295 13.1066 33.067 12.9594 29.6799H18.7707C18.816 31.9002 19.1785 34.1092 19.8469 36.2275C18.6008 36.9979 17.4566 37.9268 16.4371 38.9803ZM19.8582 21.7729C19.1898 23.8912 18.8273 26.1002 18.782 28.3205H12.9707C13.1066 24.9334 14.3301 21.6709 16.4484 19.0201C17.468 20.085 18.6121 21.0025 19.8582 21.7729ZM29.6797 24.3557C32.2059 24.2764 34.6867 23.6307 36.941 22.4752C37.5074 24.3783 37.8133 26.3381 37.8586 28.3205H29.6797V24.3557ZM29.6797 22.9963V13.1635C32.7836 14.8287 35.1285 17.6268 36.4879 21.1725C34.3809 22.2826 32.0586 22.9057 29.6797 22.985V22.9963ZM28.3203 22.985C25.9414 22.883 23.6191 22.26 21.5121 21.1498C22.8828 17.6154 25.2164 14.8174 28.3203 13.1521V22.9736V22.985ZM28.3203 24.3443V28.3205H20.1414C20.1867 26.3381 20.4926 24.3557 21.059 22.4525C23.3133 23.608 25.7828 24.2537 28.3203 24.3443ZM20.1414 29.6799H28.3203V33.6561C25.7941 33.7467 23.3133 34.3924 21.059 35.5478C20.4926 33.6447 20.1754 31.6736 20.1414 29.6799ZM28.3203 35.0154V44.8369C25.2164 43.1717 22.8828 40.385 21.5121 36.8393C23.6191 35.7291 25.9414 35.1061 28.3203 35.0041V35.0154ZM29.6797 35.0041C32.0586 35.0947 34.3922 35.7064 36.4879 36.8166C35.1172 40.3623 32.7836 43.1604 29.6797 44.8256V34.9928V35.0041ZM29.6797 33.6447V29.6799H37.8586C37.8133 31.6623 37.5074 33.6221 36.941 35.5252C34.6867 34.3697 32.2059 33.724 29.6797 33.6447ZM39.218 28.3205C39.1727 26.1002 38.8102 23.9025 38.1531 21.7955C39.3992 21.0252 40.5434 20.0963 41.5629 19.0314C43.6812 21.6822 44.8934 24.9447 45.0406 28.3318H39.2293L39.218 28.3205ZM40.668 17.9893C39.7844 18.9408 38.7762 19.7791 37.6887 20.4814C36.5219 17.5588 34.732 15.1006 32.4098 13.3221C35.5703 14.0131 38.4477 15.6443 40.668 18.0006V17.9893ZM25.5902 13.3107C23.2793 15.0893 21.4894 17.5361 20.3227 20.4588C19.2352 19.7564 18.2269 18.9295 17.332 17.9779C19.5523 15.6217 22.4297 14.0018 25.5902 13.3107ZM17.332 40.0111C18.2269 39.0709 19.2238 38.2326 20.3227 37.5303C21.4894 40.4529 23.2793 42.8998 25.5902 44.6783C22.4297 43.9873 19.5523 42.3561 17.332 40.0111ZM32.4098 44.6897C34.732 42.8998 36.5219 40.4529 37.6887 37.5303C38.7762 38.2326 39.7844 39.0709 40.668 40.0225C38.4477 42.3787 35.5703 44.01 32.4098 44.701V44.6897Z\" fill=\"#005566\"><\/path><path id=\"Vector_2\" d=\"M56.4934 24.2987L51.0219 23.7663C50.4555 21.4101 49.5152 19.1558 48.2238 17.1054L51.7242 12.8913C51.9508 12.6194 51.9281 12.2343 51.6902 11.9851L46.0828 6.29834C45.8336 6.04912 45.4371 6.02646 45.1652 6.25303L40.9398 9.75342C38.8895 8.47334 36.6352 7.52178 34.2902 6.94404L33.7578 1.43857C33.7238 1.0874 33.4406 0.815527 33.0781 0.804199H25.0238C24.6727 0.815527 24.3781 1.0874 24.3441 1.43857L23.8117 6.93271C21.4555 7.49912 19.2012 8.45068 17.1508 9.74209L12.9367 6.25303C12.6648 6.02646 12.2684 6.04912 12.0191 6.29834L6.33242 11.9851C6.0832 12.2343 6.06054 12.6308 6.28711 12.9026L9.7875 17.128C8.50742 19.1784 7.55586 21.4327 6.97812 23.7776L1.50664 24.3101C1.15547 24.344 0.894919 24.6386 0.906247 24.9897V33.044C0.906247 33.3952 1.16679 33.6897 1.50664 33.7237L6.97812 34.2561C7.54453 36.6124 8.48476 38.8667 9.77617 40.9171L6.27578 45.1311C6.04922 45.403 6.07187 45.7995 6.32109 46.0487L12.0078 51.7355C12.257 51.9847 12.6535 52.0073 12.9254 51.7808L17.1508 48.2804C19.2012 49.5605 21.4555 50.512 23.8004 51.0897L24.3328 56.5952C24.3668 56.9464 24.65 57.2183 25.0125 57.2296H33.0668C33.418 57.2183 33.7125 56.9464 33.7465 56.5952L34.2789 51.1011C36.6352 50.5347 38.8895 49.5831 40.9398 48.2917L45.1539 51.7808C45.4258 52.0073 45.8223 51.9847 46.0715 51.7355L51.7582 46.0487C52.0074 45.7995 52.0301 45.403 51.8035 45.1311L48.3031 40.9058C49.5832 38.8554 50.5348 36.6011 51.1125 34.2561L56.5047 33.7237C56.8445 33.6897 57.1164 33.3952 57.1051 33.044V24.9897C57.1051 24.6386 56.8445 24.344 56.5047 24.3101L56.4934 24.2987ZM55.7344 32.4097L50.4668 32.9308C50.1723 32.9647 49.9344 33.18 49.8777 33.4632C49.3113 36.0007 48.3031 38.4022 46.8871 40.5772C46.7285 40.8265 46.7512 41.155 46.9324 41.3815L50.3535 45.505L45.5504 50.3081L41.427 46.887C41.2004 46.6944 40.8719 46.6831 40.6113 46.8417C38.4477 48.269 36.0461 49.2886 33.5086 49.8323C33.2141 49.9116 32.9988 50.1608 32.9762 50.4554L32.4551 55.8362H25.6355L25.1145 50.4554C25.0918 50.1608 24.8766 49.9116 24.582 49.8437C22.0445 49.2772 19.643 48.2577 17.468 46.8417C17.2187 46.6831 16.8902 46.6944 16.6637 46.887L12.5402 50.3081L7.73711 45.505L11.1582 41.3815C11.3508 41.155 11.3621 40.8151 11.2035 40.5659C9.77617 38.4022 8.75664 36.0007 8.21289 33.4632C8.15625 33.18 7.91836 32.9647 7.62383 32.9308L2.27695 32.4097V25.5901L7.62383 25.069C7.91836 25.0351 8.15625 24.8198 8.21289 24.5366C8.77929 21.9991 9.7875 19.5976 11.2148 17.4226C11.3734 17.1733 11.3508 16.8448 11.1695 16.6183L7.74843 12.4948L12.5516 7.6917L16.675 11.1128C16.9016 11.3054 17.2301 11.3167 17.4906 11.1581C19.6543 9.73076 22.0559 8.71123 24.5934 8.16748C24.8879 8.08818 25.1031 7.83896 25.1258 7.54443L25.6469 2.16357H32.4664L32.9875 7.54443C33.0102 7.83896 33.2254 8.08818 33.5199 8.15615C36.0574 8.72256 38.459 9.74209 40.634 11.1581C40.8832 11.3167 41.2117 11.3054 41.4383 11.1128L45.5617 7.70303L50.3082 12.5062L46.8871 16.6409C46.6945 16.8675 46.6832 17.2073 46.8418 17.4565C48.2691 19.6202 49.2887 22.0218 49.8324 24.5593C49.8891 24.8425 50.127 25.0577 50.4215 25.0917L55.7684 25.6128V32.4323L55.7344 32.4097Z\" fill=\"#005566\"><\/path><\/g><defs><clipPath id=\"clip0_1447_4853\"><rect width=\"58\" height=\"58\" fill=\"white\"><\/rect><\/clipPath><\/defs><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-14f65bd6 elementor-widget elementor-widget-heading\" data-id=\"14f65bd6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Meilleure exp\u00e9rience client\n\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-25049107 elementor-widget elementor-widget-text-editor\" data-id=\"25049107\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400\">Une planification optimale du personnel et des marchandises r\u00e9duit les temps d\u2019attente et am\u00e9liore la qualit\u00e9 du service.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-32238233 e-con-full e-flex e-con e-child\" data-id=\"32238233\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-25300fee elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"25300fee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"58\" height=\"58\" viewBox=\"0 0 58 58\" fill=\"none\"><g id=\"smartphone-2 1\"><path id=\"Vector\" d=\"M45.0859 6.79688C45.0859 3.91953 42.7523 1.58594 39.875 1.58594H18.125C15.2477 1.58594 12.9141 3.91953 12.9141 6.79688V51.0898C12.9141 53.9672 15.2477 56.3008 18.125 56.3008H39.875C42.7523 56.3008 45.0859 53.9672 45.0859 51.0898V6.79688ZM43.7266 44.293H14.2734V11.8945H43.7266V44.293ZM39.8863 55.0547H18.1023C15.984 55.0547 14.2621 53.2875 14.2621 51.1578V45.6523H43.7152V51.1578C43.7152 53.2762 42.0047 55.0547 39.875 55.0547H39.8863ZM43.7266 10.5352H14.2734V6.84219C14.2734 4.72383 15.984 2.94531 18.1137 2.94531H39.8977C42.016 2.94531 43.7379 4.7125 43.7379 6.84219V10.5352H43.7266Z\" fill=\"#005566\"><\/path><path id=\"Vector_2\" d=\"M32.8516 5.77734H25.1371C24.7633 5.77734 24.4574 6.0832 24.4574 6.45703C24.4574 6.83086 24.7633 7.13672 25.1371 7.13672H32.8516C33.2254 7.13672 33.5313 6.83086 33.5313 6.45703C33.5313 6.0832 33.2254 5.77734 32.8516 5.77734Z\" fill=\"#005566\"><\/path><path id=\"Vector_3\" d=\"M29 47.3062C27.3121 47.3062 25.9527 48.6769 25.9527 50.3534C25.9527 52.03 27.3234 53.4007 29 53.4007C30.6879 53.4007 32.0473 52.03 32.0473 50.3534C32.0473 48.6655 30.6766 47.3062 29 47.3062ZM29 52.0526C28.0598 52.0526 27.3121 51.2937 27.3121 50.3647C27.3121 49.4358 28.0711 48.6769 29 48.6769C29.9402 48.6769 30.6879 49.4358 30.6879 50.3647C30.6879 51.305 29.9289 52.0526 29 52.0526Z\" fill=\"#005566\"><\/path><path id=\"Vector_4\" d=\"M21.3762 37.8019L28.6148 42.7409C28.8527 42.8995 29.1473 42.8995 29.3851 42.7409L36.6351 37.8019C38.8328 36.3065 40.566 33.0554 40.566 30.3933V20.2433C40.566 19.9827 40.4074 19.7448 40.1809 19.6315L29.3172 14.296C29.1246 14.2054 28.9094 14.2054 28.7168 14.296L17.8531 19.6089C17.6152 19.7222 17.468 19.9601 17.4566 20.2206V30.3933C17.4566 33.044 19.1898 36.2952 21.3875 37.8019H21.3762ZM18.8047 20.6511L29 15.6667L39.1953 20.6624V30.3933C39.1953 32.5683 37.666 35.4456 35.8648 36.669L29.0113 41.3476L22.1465 36.669C20.3453 35.4456 18.816 32.5683 18.816 30.3933V20.6511H18.8047Z\" fill=\"#005566\"><\/path><path id=\"Vector_5\" d=\"M29 36.3295C33.3047 36.3295 36.7824 32.8404 36.7824 28.5471C36.7824 24.2424 33.2934 20.7646 29 20.7646C24.7067 20.7646 21.2176 24.2537 21.2176 28.5471C21.2176 32.8404 24.7067 36.3295 29 36.3295ZM29 22.124C32.5457 22.124 35.4231 25.0014 35.4231 28.5471C35.4231 32.0928 32.5457 34.9701 29 34.9701C25.4543 34.9701 22.577 32.0928 22.577 28.5471C22.577 25.0014 25.4543 22.124 29 22.124Z\" fill=\"#005566\"><\/path><path id=\"Vector_6\" d=\"M27.4707 31.0733C27.7312 31.3338 28.1504 31.3451 28.4223 31.0959L32.7723 26.9838C33.0441 26.7233 33.0668 26.2928 32.8062 26.0209C32.5457 25.7491 32.1152 25.7264 31.8434 25.9869L27.9805 29.6346L26.168 27.7768C25.9074 27.5049 25.4769 27.5049 25.2051 27.7655C24.9332 28.026 24.9332 28.4565 25.1937 28.7283L27.4707 31.0733Z\" fill=\"#005566\"><\/path><\/g><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7eec1b68 elementor-widget elementor-widget-heading\" data-id=\"7eec1b68\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Modulaire et extensible avec flexibilit\u00e9\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-69bc7ffc elementor-widget elementor-widget-text-editor\" data-id=\"69bc7ffc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400\">Mirus Prognolite \u00e9volue avec votre entreprise et s\u2019int\u00e8gre de mani\u00e8re transparente aux syst\u00e8mes existants.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7bc9aceb e-con-full e-flex e-con e-parent\" data-id=\"7bc9aceb\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6beacc36 elementor-widget elementor-widget-image\" data-id=\"6beacc36\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"2560\" height=\"2006\" src=\"https:\/\/mirus.ch\/wp-content\/uploads\/2025\/07\/dersktop-3.webp\" class=\"attachment-full size-full wp-image-8216\" alt=\"\" srcset=\"https:\/\/mirus.ch\/wp-content\/uploads\/2025\/07\/dersktop-3.webp 2560w, https:\/\/mirus.ch\/wp-content\/uploads\/2025\/07\/dersktop-3-300x235.webp 300w, https:\/\/mirus.ch\/wp-content\/uploads\/2025\/07\/dersktop-3-1024x802.webp 1024w, https:\/\/mirus.ch\/wp-content\/uploads\/2025\/07\/dersktop-3-768x602.webp 768w, https:\/\/mirus.ch\/wp-content\/uploads\/2025\/07\/dersktop-3-1536x1204.webp 1536w, https:\/\/mirus.ch\/wp-content\/uploads\/2025\/07\/dersktop-3-2048x1605.webp 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7a8068c7 e-flex e-con-boxed e-con e-parent\" data-id=\"7a8068c7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0ab58e1 elementor-widget elementor-widget-menu-anchor\" data-id=\"0ab58e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"form\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4ee235d3 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"4ee235d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Vous \u00eates int\u00e9ress\u00e9 par Mirus Prognolite et souhaitez en savoir plus ? Nous nous r\u00e9jouissons de votre message ! <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7076dbe1 e-con-full e-flex e-con e-child\" data-id=\"7076dbe1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1440ad8f elementor-button-align-start elementor-mobile-button-align-start elementor-widget elementor-widget-form\" data-id=\"1440ad8f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Suivant&quot;,&quot;step_previous_label&quot;:&quot;Pr\\u00e9c\\u00e9dent&quot;,&quot;step_icon_shape&quot;:&quot;square&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"Formulaire de contact\" aria-label=\"Formulaire de contact\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"8273\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"1440ad8f\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"Mirus Prognolite | Mirus\" \/>\n\n\t\t\t\t\t\t\t<input type=\"hidden\" name=\"queried_id\" value=\"8273\"\/>\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-50 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-name\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tNom\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-xs  elementor-field-textual\" placeholder=\"Nom\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-field_d851074 elementor-col-50 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_d851074\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tEntreprise\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[field_d851074]\" id=\"form-field-field_d851074\" class=\"elementor-field elementor-size-xs  elementor-field-textual\" placeholder=\"Entreprise\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-50 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tE-mail\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-xs  elementor-field-textual\" placeholder=\"E-mail\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-tel elementor-field-group elementor-column elementor-field-group-field_02d0106 elementor-col-50 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_02d0106\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tT\u00e9l\u00e9phone\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<input size=\"1\" type=\"tel\" name=\"form_fields[field_02d0106]\" id=\"form-field-field_02d0106\" class=\"elementor-field elementor-size-xs  elementor-field-textual\" placeholder=\"T\u00e9l\u00e9phone\" required=\"required\" pattern=\"[0-9()#&amp;+*-=.]+\" title=\"Seuls les caract\u00e8res de num\u00e9ros de t\u00e9l\u00e9phone (#, -, *, etc.) sont accept\u00e9s.\">\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-textarea elementor-field-group elementor-column elementor-field-group-message elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-message\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tMessage\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<textarea class=\"elementor-field-textual elementor-field  elementor-size-xs\" name=\"form_fields[message]\" id=\"form-field-message\" rows=\"4\" placeholder=\"Message\"><\/textarea>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-recaptcha elementor-field-group elementor-column elementor-field-group-field_a75ba6c elementor-col-100\">\n\t\t\t\t\t<div class=\"elementor-field\" id=\"form-field-field_a75ba6c\"><div class=\"elementor-g-recaptcha\" data-sitekey=\"6Lcs3LUrAAAAANFB1ySo4WPx0NeTWJGVGJP3OJsp\" data-type=\"v2_checkbox\" data-theme=\"light\" data-size=\"normal\"><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-md\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Envoyer maintenant !<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-25180c0 e-flex e-con-boxed e-con e-parent\" data-id=\"25180c0\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-73564cce e-flex e-con-boxed e-con e-child\" data-id=\"73564cce\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-46815195 elementor-widget elementor-widget-heading\" data-id=\"46815195\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Inform\u00e9 rapidement<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-581e070d elementor-widget elementor-widget-heading\" data-id=\"581e070d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Avez-vous des questions sur Mirus Prognolite ?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2c4aae6b e-con-full e-flex e-con e-child\" data-id=\"2c4aae6b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2b2c0284 elementor-widget elementor-widget-n-accordion\" data-id=\"2b2c0284\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:200,&quot;sizes&quot;:[]},&quot;default_state&quot;:&quot;expanded&quot;,&quot;max_items_expended&quot;:&quot;one&quot;}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-7240\" class=\"e-n-accordion-item\" open>\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"true\" aria-controls=\"e-n-accordion-item-7240\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Qu\u2019est-ce que Mirus Prognolite ? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-7240\" class=\"elementor-element elementor-element-709ed08c e-con-full e-flex e-con e-child\" data-id=\"709ed08c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-534752fe elementor-widget elementor-widget-text-editor\" data-id=\"534752fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400\">Mirus Prognolite est une solution logicielle bas\u00e9e sur l\u2019IA pour la restauration et l\u2019h\u00f4tellerie, offrant des pr\u00e9visions pr\u00e9cises de chiffre d\u2019affaires et de personnel, une planification des services ainsi que des analyses compl\u00e8tes pour une gestion op\u00e9rationnelle efficace.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-7241\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-7241\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Comment fonctionne l\u2019int\u00e9gration dans les syst\u00e8mes existants ? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-7241\" class=\"elementor-element elementor-element-482723e6 e-con-full e-flex e-con e-child\" data-id=\"482723e6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3fb38b8c elementor-widget elementor-widget-text-editor\" data-id=\"3fb38b8c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400\">Mirus Prognolite int\u00e8gre les syst\u00e8mes de caisse, PMS et front-office existants. Toutes les donn\u00e9es pertinentes sont regroup\u00e9es de mani\u00e8re claire dans un tableau de bord central. Les erreurs de transfert manuel et les silos de donn\u00e9es sont ainsi \u00e9vit\u00e9s.  <\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-7242\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"3\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-7242\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Quelles donn\u00e9es sont utilis\u00e9es pour les pr\u00e9visions ? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-7242\" class=\"elementor-element elementor-element-57502053 e-flex e-con-boxed e-con e-child\" data-id=\"57502053\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-798f6004 elementor-widget elementor-widget-text-editor\" data-id=\"798f6004\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400\">Le logiciel analyse les donn\u00e9es historiques de caisse, PMS et de front-office, ainsi que les informations actuelles sur la m\u00e9t\u00e9o, les vacances et les jours f\u00e9ri\u00e9s. Il en r\u00e9sulte des pr\u00e9visions fond\u00e9es et orient\u00e9es vers l\u2019avenir, qui tiennent compte des fluctuations saisonni\u00e8res et des influences externes. <\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-7243\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"4\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-7243\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Puis-je \u00e9galement mesurer la productivit\u00e9 de mon \u00e9quipe avec Mirus Prognolite ? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-7243\" class=\"elementor-element elementor-element-4ebe3008 e-flex e-con-boxed e-con e-child\" data-id=\"4ebe3008\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7c67de2 elementor-widget elementor-widget-text-editor\" data-id=\"7c67de2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400\">Oui, Mirus Prognolite mesure la productivit\u00e9 de vos collaborateurs sur la base d\u2019indicateurs cl\u00e9s tels que le chiffre d\u2019affaires par heure de travail. Vous pouvez comparer les performances sur diff\u00e9rentes p\u00e9riodes, identifier les tendances et en d\u00e9duire des formations cibl\u00e9es. <\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-7244\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"5\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-7244\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Mirus Prognolite convient-il \u00e9galement \u00e0 plusieurs sites ? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-7244\" class=\"elementor-element elementor-element-18ea65ab e-flex e-con-boxed e-con e-child\" data-id=\"18ea65ab\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-59ebbad6 elementor-widget elementor-widget-text-editor\" data-id=\"59ebbad6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400\">Oui, la solution web permet une utilisation multisite. Vous pouvez piloter plusieurs \u00e9tablissements de mani\u00e8re centralis\u00e9e et surveiller tous les indicateurs cl\u00e9s dans un tableau de bord. <\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-7245\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"6\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-7245\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Comment Mirus Prognolite aide-t-il \u00e0 r\u00e9duire le gaspillage alimentaire ? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-7245\" class=\"elementor-element elementor-element-564e5fc e-flex e-con-boxed e-con e-child\" data-id=\"564e5fc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1b7bb950 elementor-widget elementor-widget-text-editor\" data-id=\"1b7bb950\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400\">Gr\u00e2ce \u00e0 des pr\u00e9visions pr\u00e9cises de la fr\u00e9quentation et du chiffre d\u2019affaires, vous pouvez planifier vos besoins en marchandises en fonction des besoins et ainsi r\u00e9duire durablement le gaspillage alimentaire et les co\u00fbts inutiles.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-7246\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"7\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-7246\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> \u00c0 quelle vitesse puis-je d\u00e9marrer avec Mirus Prognolite ? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-7246\" class=\"elementor-element elementor-element-7446f442 e-flex e-con-boxed e-con e-child\" data-id=\"7446f442\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5568dcb2 elementor-widget elementor-widget-text-editor\" data-id=\"5568dcb2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400\">Gr\u00e2ce \u00e0 l\u2019interface utilisateur intuitive et \u00e0 l\u2019int\u00e9gration facile dans les syst\u00e8mes existants, une prise en main rapide est possible. M\u00eame les nouveaux collaborateurs s\u2019y retrouvent rapidement, sans avoir besoin de connaissances informatiques approfondies. <\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Mirus Prognolite \u2013 La plateforme de pr\u00e9vision &amp; d\u2019analyse pour l\u2019h\u00f4tellerie &amp; la restauration Des pr\u00e9visions pr\u00e9cises, de meilleures d\u00e9cisions Pr\u00e9visions de chiffre d\u2019affaires et de personnel bas\u00e9es sur l\u2019IA pour votre entreprise Mirus Prognolite est la solution intelligente qui r\u00e9volutionne votre planification du chiffre d\u2019affaires et du personnel dans l\u2019h\u00f4tellerie-restauration. Exploitez la puissance de [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":8298,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"event":[],"class_list":["post-8273","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mirus Prognolite | Mirus<\/title>\n<meta name=\"description\" content=\"La plateforme de pr\u00e9vision pour la restauration et l\u2019h\u00f4tellerie : hub de donn\u00e9es bas\u00e9 sur l\u2019IA &amp; interfaces pour des pr\u00e9visions pr\u00e9cises du chiffre d\u2019affaires &amp; du personnel et une planification optimale.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mirus.ch\/fr\/produits\/mirus-prognolite\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mirus Prognolite | Mirus\" \/>\n<meta property=\"og:description\" content=\"La plateforme de pr\u00e9vision pour la restauration et l\u2019h\u00f4tellerie : hub de donn\u00e9es bas\u00e9 sur l\u2019IA &amp; interfaces pour des pr\u00e9visions pr\u00e9cises du chiffre d\u2019affaires &amp; du personnel et une planification optimale.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mirus.ch\/fr\/produits\/mirus-prognolite\/\" \/>\n<meta property=\"og:site_name\" content=\"Mirus\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-18T07:04:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mirus.ch\/wp-content\/uploads\/2025\/07\/dersktop-3.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"2006\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mirus.ch\\\/fr\\\/produits\\\/mirus-prognolite\\\/\",\"url\":\"https:\\\/\\\/mirus.ch\\\/fr\\\/produits\\\/mirus-prognolite\\\/\",\"name\":\"Mirus Prognolite | Mirus\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mirus.ch\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mirus.ch\\\/fr\\\/produits\\\/mirus-prognolite\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mirus.ch\\\/fr\\\/produits\\\/mirus-prognolite\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mirus.ch\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/dersktop-3.webp\",\"datePublished\":\"2025-06-27T09:58:49+00:00\",\"dateModified\":\"2026-08-18T07:04:14+00:00\",\"description\":\"La plateforme de pr\u00e9vision pour la restauration et l\u2019h\u00f4tellerie : hub de donn\u00e9es bas\u00e9 sur l\u2019IA & interfaces pour des pr\u00e9visions pr\u00e9cises du chiffre d\u2019affaires & du personnel et une planification optimale.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mirus.ch\\\/fr\\\/produits\\\/mirus-prognolite\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mirus.ch\\\/fr\\\/produits\\\/mirus-prognolite\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mirus.ch\\\/fr\\\/produits\\\/mirus-prognolite\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mirus.ch\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/dersktop-3.webp\",\"contentUrl\":\"https:\\\/\\\/mirus.ch\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/dersktop-3.webp\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mirus.ch\\\/fr\\\/produits\\\/mirus-prognolite\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mirus.ch\\\/fr\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/mirus.ch\\\/fr\\\/produkte\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Mirus Prognolite\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mirus.ch\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/mirus.ch\\\/fr\\\/\",\"name\":\"Mirus Software AG\",\"description\":\"Software und Service mit Herzblut\",\"publisher\":{\"@id\":\"https:\\\/\\\/mirus.ch\\\/fr\\\/#organization\"},\"alternateName\":\"Mirus Schweiz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mirus.ch\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mirus.ch\\\/fr\\\/#organization\",\"name\":\"Mirus software AG\",\"url\":\"https:\\\/\\\/mirus.ch\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mirus.ch\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mirus.ch\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/mirus-logo-rgb-turquise.png\",\"contentUrl\":\"https:\\\/\\\/mirus.ch\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/mirus-logo-rgb-turquise.png\",\"width\":529,\"height\":123,\"caption\":\"Mirus software AG\"},\"image\":{\"@id\":\"https:\\\/\\\/mirus.ch\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/mirussoftwareag\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mirus Prognolite | Mirus","description":"La plateforme de pr\u00e9vision pour la restauration et l\u2019h\u00f4tellerie : hub de donn\u00e9es bas\u00e9 sur l\u2019IA & interfaces pour des pr\u00e9visions pr\u00e9cises du chiffre d\u2019affaires & du personnel et une planification optimale.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mirus.ch\/fr\/produits\/mirus-prognolite\/","og_locale":"fr_FR","og_type":"article","og_title":"Mirus Prognolite | Mirus","og_description":"La plateforme de pr\u00e9vision pour la restauration et l\u2019h\u00f4tellerie : hub de donn\u00e9es bas\u00e9 sur l\u2019IA & interfaces pour des pr\u00e9visions pr\u00e9cises du chiffre d\u2019affaires & du personnel et une planification optimale.","og_url":"https:\/\/mirus.ch\/fr\/produits\/mirus-prognolite\/","og_site_name":"Mirus","article_modified_time":"2026-08-18T07:04:14+00:00","og_image":[{"width":2560,"height":2006,"url":"https:\/\/mirus.ch\/wp-content\/uploads\/2025\/07\/dersktop-3.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mirus.ch\/fr\/produits\/mirus-prognolite\/","url":"https:\/\/mirus.ch\/fr\/produits\/mirus-prognolite\/","name":"Mirus Prognolite | Mirus","isPartOf":{"@id":"https:\/\/mirus.ch\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mirus.ch\/fr\/produits\/mirus-prognolite\/#primaryimage"},"image":{"@id":"https:\/\/mirus.ch\/fr\/produits\/mirus-prognolite\/#primaryimage"},"thumbnailUrl":"https:\/\/mirus.ch\/wp-content\/uploads\/2025\/07\/dersktop-3.webp","datePublished":"2025-06-27T09:58:49+00:00","dateModified":"2026-08-18T07:04:14+00:00","description":"La plateforme de pr\u00e9vision pour la restauration et l\u2019h\u00f4tellerie : hub de donn\u00e9es bas\u00e9 sur l\u2019IA & interfaces pour des pr\u00e9visions pr\u00e9cises du chiffre d\u2019affaires & du personnel et une planification optimale.","breadcrumb":{"@id":"https:\/\/mirus.ch\/fr\/produits\/mirus-prognolite\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mirus.ch\/fr\/produits\/mirus-prognolite\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mirus.ch\/fr\/produits\/mirus-prognolite\/#primaryimage","url":"https:\/\/mirus.ch\/wp-content\/uploads\/2025\/07\/dersktop-3.webp","contentUrl":"https:\/\/mirus.ch\/wp-content\/uploads\/2025\/07\/dersktop-3.webp"},{"@type":"BreadcrumbList","@id":"https:\/\/mirus.ch\/fr\/produits\/mirus-prognolite\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mirus.ch\/fr\/home\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/mirus.ch\/fr\/produkte\/"},{"@type":"ListItem","position":3,"name":"Mirus Prognolite"}]},{"@type":"WebSite","@id":"https:\/\/mirus.ch\/fr\/#website","url":"https:\/\/mirus.ch\/fr\/","name":"Mirus Software AG","description":"Software und Service mit Herzblut","publisher":{"@id":"https:\/\/mirus.ch\/fr\/#organization"},"alternateName":"Mirus Schweiz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mirus.ch\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/mirus.ch\/fr\/#organization","name":"Mirus software AG","url":"https:\/\/mirus.ch\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mirus.ch\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/mirus.ch\/wp-content\/uploads\/2025\/07\/mirus-logo-rgb-turquise.png","contentUrl":"https:\/\/mirus.ch\/wp-content\/uploads\/2025\/07\/mirus-logo-rgb-turquise.png","width":529,"height":123,"caption":"Mirus software AG"},"image":{"@id":"https:\/\/mirus.ch\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/mirussoftwareag\/"]}]}},"_links":{"self":[{"href":"https:\/\/mirus.ch\/fr\/wp-json\/wp\/v2\/pages\/8273","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mirus.ch\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mirus.ch\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mirus.ch\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/mirus.ch\/fr\/wp-json\/wp\/v2\/comments?post=8273"}],"version-history":[{"count":22,"href":"https:\/\/mirus.ch\/fr\/wp-json\/wp\/v2\/pages\/8273\/revisions"}],"predecessor-version":[{"id":14904,"href":"https:\/\/mirus.ch\/fr\/wp-json\/wp\/v2\/pages\/8273\/revisions\/14904"}],"up":[{"embeddable":true,"href":"https:\/\/mirus.ch\/fr\/wp-json\/wp\/v2\/pages\/8298"}],"wp:attachment":[{"href":"https:\/\/mirus.ch\/fr\/wp-json\/wp\/v2\/media?parent=8273"}],"wp:term":[{"taxonomy":"event","embeddable":true,"href":"https:\/\/mirus.ch\/fr\/wp-json\/wp\/v2\/event?post=8273"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}